{"id":22595,"date":"2019-09-14T11:09:13","date_gmt":"2019-09-14T09:09:13","guid":{"rendered":"https:\/\/www.irenemilito.it\/?p=22595"},"modified":"2019-09-14T11:09:13","modified_gmt":"2019-09-14T09:09:13","slug":"pizza-classica","status":"publish","type":"post","link":"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/","title":{"rendered":"Pizza cl\u00e1ssica"},"content":{"rendered":"<p><strong>Ingredientes para a massa:<\/strong><\/p>\n<ul>\n<li>1 tablete de fermento Fleischmann<\/li>\n<li>1 copo de leite<\/li>\n<li>1 ovo inteiro<\/li>\n<li>1 colher das de sopa de margarina<\/li>\n<li>1 colherinha de sal<\/li>\n<\/ul>\n<p><strong>Ingredientes para o recheio:<\/strong><\/p>\n<ul>\n<li>1\/2 kg de tomates cortados em rodelas temperados com sal o or\u00e9gano<\/li>\n<li>1\/2 kg de mussarela em fatias<\/li>\n<\/ul>\n<p><strong>Modo de preparo da massa:<\/strong><\/p>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Farinha de trigo, aos poucos para engrossar, porque esta massa devera\u0301 ficar mais mole que a massa de torta. Deixe descansar, enquanto voce\u0302 prepara o resto.<\/p>\n<p><strong>Modo de preparo da pizza:<\/strong><\/p>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Unte bem uma assadeira e com as ma\u0303os tambe\u0301m untadas, va\u0301 abrindo a massa dentro da assadeira, apertando ate\u0301 cobri-la toda. Quando estiver inteirinha coberta, coloque os tomates bem juntinhos, regando com o restinho do tempero que ficou e azeite. Por cima, a mussarela cobrindo toda a massa. Assar em forno me\u0301dio, primeiro por baixo, depois quando a massa estiver assada, ligue-o por cima, para que o queijo derreta bem.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ingredientes para a massa: 1 tablete de fermento Fleischmann 1 copo de leite 1 ovo inteiro 1 colher das de sopa de margarina 1 colherinha de sal Ingredientes para o recheio: 1\/2 kg de tomates cortados em rodelas temperados com sal o or\u00e9gano 1\/2 kg de mussarela em fatias Modo de preparo da massa: Farinha&#8230;<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/\">Read More<\/a><\/div>\n","protected":false},"author":3,"featured_media":22596,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[13792],"tags":[14055,14056,14060,14059,14057,14049,13797,14053,14054,14050,14051,14052,14058],"class_list":["post-22595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-receitas","tag-fermento-fleischmann","tag-leite","tag-margarina-pt-pt","tag-mussarela-em-fatias","tag-ovo-inteiro","tag-pizza-classica","tag-receitas","tag-receitas-com-massa-de-pizza","tag-receitas-com-recheio","tag-receitas-massas","tag-receitas-pizza","tag-recetas-classicas","tag-tomates-cortados-em-rodelas-temperados-com-sal-o-oregano"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pizza cl\u00e1ssica - IreneMilito.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pizza cl\u00e1ssica\" \/>\n<meta property=\"og:description\" content=\"Ingredientes para a massa: 1 tablete de fermento Fleischmann 1 copo de leite 1 ovo inteiro 1 colher das de sopa de margarina 1 colherinha de sal Ingredientes para o recheio: 1\/2 kg de tomates cortados em rodelas temperados com sal o or\u00e9gano 1\/2 kg de mussarela em fatias Modo de preparo da massa: Farinha...Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/\" \/>\n<meta property=\"og:site_name\" content=\"IreneMilito.it\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-14T09:09:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/09\/IMG_0291-720x720.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Milito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Milito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/\",\"url\":\"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/\",\"name\":\"Pizza cl\u00e1ssica - IreneMilito.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.irenemilito.it\/pt-pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/09\/IMG_0291-720x720.jpg\",\"datePublished\":\"2019-09-14T09:09:13+00:00\",\"dateModified\":\"2019-09-14T09:09:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.irenemilito.it\/pt-pt\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/#primaryimage\",\"url\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/09\/IMG_0291-720x720.jpg\",\"contentUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/09\/IMG_0291-720x720.jpg\",\"width\":720,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.irenemilito.it\/pt-pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pizza cl\u00e1ssica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irenemilito.it\/pt-pt\/#website\",\"url\":\"https:\/\/www.irenemilito.it\/pt-pt\/\",\"name\":\"IreneMilito.it\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irenemilito.it\/pt-pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.irenemilito.it\/pt-pt\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\",\"name\":\"Irene Milito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.irenemilito.it\/pt-pt\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"caption\":\"Irene Milito\"},\"url\":\"https:\/\/www.irenemilito.it\/pt-pt\/author\/irene-milito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pizza cl\u00e1ssica - IreneMilito.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/","og_locale":"pt_PT","og_type":"article","og_title":"Pizza cl\u00e1ssica","og_description":"Ingredientes para a massa: 1 tablete de fermento Fleischmann 1 copo de leite 1 ovo inteiro 1 colher das de sopa de margarina 1 colherinha de sal Ingredientes para o recheio: 1\/2 kg de tomates cortados em rodelas temperados com sal o or\u00e9gano 1\/2 kg de mussarela em fatias Modo de preparo da massa: Farinha...Read More","og_url":"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/","og_site_name":"IreneMilito.it","article_published_time":"2019-09-14T09:09:13+00:00","og_image":[{"width":720,"height":720,"url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/09\/IMG_0291-720x720.jpg","type":"image\/jpeg"}],"author":"Irene Milito","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Irene Milito","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/","url":"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/","name":"Pizza cl\u00e1ssica - IreneMilito.it","isPartOf":{"@id":"https:\/\/www.irenemilito.it\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/#primaryimage"},"image":{"@id":"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/09\/IMG_0291-720x720.jpg","datePublished":"2019-09-14T09:09:13+00:00","dateModified":"2019-09-14T09:09:13+00:00","author":{"@id":"https:\/\/www.irenemilito.it\/pt-pt\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43"},"breadcrumb":{"@id":"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/#primaryimage","url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/09\/IMG_0291-720x720.jpg","contentUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/09\/IMG_0291-720x720.jpg","width":720,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.irenemilito.it\/pt-pt\/pizza-classica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irenemilito.it\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Pizza cl\u00e1ssica"}]},{"@type":"WebSite","@id":"https:\/\/www.irenemilito.it\/pt-pt\/#website","url":"https:\/\/www.irenemilito.it\/pt-pt\/","name":"IreneMilito.it","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irenemilito.it\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/www.irenemilito.it\/pt-pt\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43","name":"Irene Milito","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.irenemilito.it\/pt-pt\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","caption":"Irene Milito"},"url":"https:\/\/www.irenemilito.it\/pt-pt\/author\/irene-milito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.irenemilito.it\/pt-pt\/wp-json\/wp\/v2\/posts\/22595"}],"collection":[{"href":"https:\/\/www.irenemilito.it\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irenemilito.it\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/pt-pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/pt-pt\/wp-json\/wp\/v2\/comments?post=22595"}],"version-history":[{"count":1,"href":"https:\/\/www.irenemilito.it\/pt-pt\/wp-json\/wp\/v2\/posts\/22595\/revisions"}],"predecessor-version":[{"id":22600,"href":"https:\/\/www.irenemilito.it\/pt-pt\/wp-json\/wp\/v2\/posts\/22595\/revisions\/22600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/pt-pt\/wp-json\/wp\/v2\/media\/22596"}],"wp:attachment":[{"href":"https:\/\/www.irenemilito.it\/pt-pt\/wp-json\/wp\/v2\/media?parent=22595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irenemilito.it\/pt-pt\/wp-json\/wp\/v2\/categories?post=22595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irenemilito.it\/pt-pt\/wp-json\/wp\/v2\/tags?post=22595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}