{"id":29217,"date":"2020-09-25T10:00:09","date_gmt":"2020-09-25T08:00:09","guid":{"rendered":"https:\/\/www.irenemilito.it\/?p=29217"},"modified":"2020-09-24T18:17:59","modified_gmt":"2020-09-24T16:17:59","slug":"bifes-a-la-portuguesa","status":"publish","type":"post","link":"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/","title":{"rendered":"Bifes a la portuguesa"},"content":{"rendered":"<p><strong>Ingredientes:<\/strong><\/p>\n<ul>\n<li>250 g de carne tierna (babilla, croca) (yo utilic\u00e9 Ternera Gallega)<\/li>\n<li>1 cebolla<\/li>\n<li>3 dientes de ajo<\/li>\n<li>\u00bd vaso de salsa de tomate casera o de tomate triturado ( los de Mercadona que son buen\u00edsimos)<\/li>\n<li>\u00bd pimiento verde<\/li>\n<li>\u00bd pimiento rojo<\/li>\n<li>2 chalotas (opcional)<\/li>\n<li>1 tomate fresco<\/li>\n<li>Or\u00e9gano fresco<\/li>\n<li>\u00bd chile<\/li>\n<li>Perejil<\/li>\n<li>Sal<\/li>\n<li>Pimienta negra (reci\u00e9n molida)<\/li>\n<li>Chorrito de vino blanco<\/li>\n<li>Aceite de Oliva Virgen Extra<\/li>\n<\/ul>\n<p><b>Preparaci\u00f3n:<\/b><\/p>\n<p>En una sart\u00e9n con un chorro de aceite dorar a fuego fuerte la carne cortada en bastoncitos y espolvoreada con pimienta, apenas un dorado r\u00e1pido. Retirar y reservar. En la misma sart\u00e9n (si fuese necesario a\u00f1adir un poco m\u00e1s de aceite) sofre\u00edr la cebolla cortada en trozos grandes, salpimentar. A\u00f1adir los pimientos cortados en juliana, el trozo de chile entero, las chalotas cortadas y los dientes de ajo picados. Agregar el vino, dejar evaporar y a\u00f1adir el tomate fresco cortado en trozos grandes, incorporar la salsa de tomate o el tomate triturado, una ramita de or\u00e9gano fresco, salpimentar y dejar a fuego bajo en chup-chup durante 12 minutos. A\u00f1adir los bastoncitos de carne que hab\u00edamos dorado, dejar 2-3 minutos (no queremos que una carne tierna quede pasada de cocci\u00f3n) rectificamos de sal, retiramos el chile, espolvoreamos perejil picadito y servimos caliente. Acompa\u00f1amos con patatas fritas, arroz blanco o pasta<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingredientes: 250 g de carne tierna (babilla, croca) (yo utilic\u00e9 Ternera Gallega) 1 cebolla 3 dientes de ajo \u00bd vaso de salsa de tomate casera o de tomate triturado ( los de Mercadona que son buen\u00edsimos) \u00bd pimiento verde \u00bd pimiento rojo 2 chalotas (opcional) 1 tomate fresco Or\u00e9gano fresco \u00bd chile Perejil Sal Pimienta&#8230;<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/\">Read More<\/a><\/div>\n","protected":false},"author":3,"featured_media":29218,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3800],"tags":[],"class_list":["post-29217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bifes a la portuguesa - IreneMilito.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bifes a la portuguesa\" \/>\n<meta property=\"og:description\" content=\"Ingredientes: 250 g de carne tierna (babilla, croca) (yo utilic\u00e9 Ternera Gallega) 1 cebolla 3 dientes de ajo \u00bd vaso de salsa de tomate casera o de tomate triturado ( los de Mercadona que son buen\u00edsimos) \u00bd pimiento verde \u00bd pimiento rojo 2 chalotas (opcional) 1 tomate fresco Or\u00e9gano fresco \u00bd chile Perejil Sal Pimienta...Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/\" \/>\n<meta property=\"og:site_name\" content=\"IreneMilito.it\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-25T08:00:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-24T16:17:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/119939720_141040751060016_2400177704335178421_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"705\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Milito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Milito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/\",\"url\":\"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/\",\"name\":\"Bifes a la portuguesa - IreneMilito.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/119939720_141040751060016_2400177704335178421_n.jpg\",\"datePublished\":\"2020-09-25T08:00:09+00:00\",\"dateModified\":\"2020-09-24T16:17:59+00:00\",\"author\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/#primaryimage\",\"url\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/119939720_141040751060016_2400177704335178421_n.jpg\",\"contentUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/119939720_141040751060016_2400177704335178421_n.jpg\",\"width\":720,\"height\":705},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.irenemilito.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bifes a la portuguesa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\",\"url\":\"https:\/\/www.irenemilito.it\/es\/\",\"name\":\"IreneMilito.it\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\",\"name\":\"Irene Milito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"caption\":\"Irene Milito\"},\"url\":\"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bifes a la portuguesa - IreneMilito.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/","og_locale":"es_ES","og_type":"article","og_title":"Bifes a la portuguesa","og_description":"Ingredientes: 250 g de carne tierna (babilla, croca) (yo utilic\u00e9 Ternera Gallega) 1 cebolla 3 dientes de ajo \u00bd vaso de salsa de tomate casera o de tomate triturado ( los de Mercadona que son buen\u00edsimos) \u00bd pimiento verde \u00bd pimiento rojo 2 chalotas (opcional) 1 tomate fresco Or\u00e9gano fresco \u00bd chile Perejil Sal Pimienta...Read More","og_url":"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/","og_site_name":"IreneMilito.it","article_published_time":"2020-09-25T08:00:09+00:00","article_modified_time":"2020-09-24T16:17:59+00:00","og_image":[{"width":720,"height":705,"url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/119939720_141040751060016_2400177704335178421_n.jpg","type":"image\/jpeg"}],"author":"Irene Milito","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Irene Milito","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/","url":"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/","name":"Bifes a la portuguesa - IreneMilito.it","isPartOf":{"@id":"https:\/\/www.irenemilito.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/#primaryimage"},"image":{"@id":"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/119939720_141040751060016_2400177704335178421_n.jpg","datePublished":"2020-09-25T08:00:09+00:00","dateModified":"2020-09-24T16:17:59+00:00","author":{"@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43"},"breadcrumb":{"@id":"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/#primaryimage","url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/119939720_141040751060016_2400177704335178421_n.jpg","contentUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/119939720_141040751060016_2400177704335178421_n.jpg","width":720,"height":705},{"@type":"BreadcrumbList","@id":"https:\/\/www.irenemilito.it\/es\/bifes-a-la-portuguesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irenemilito.it\/es\/"},{"@type":"ListItem","position":2,"name":"Bifes a la portuguesa"}]},{"@type":"WebSite","@id":"https:\/\/www.irenemilito.it\/es\/#website","url":"https:\/\/www.irenemilito.it\/es\/","name":"IreneMilito.it","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43","name":"Irene Milito","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","caption":"Irene Milito"},"url":"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/29217"}],"collection":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/comments?post=29217"}],"version-history":[{"count":1,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/29217\/revisions"}],"predecessor-version":[{"id":29222,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/29217\/revisions\/29222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media\/29218"}],"wp:attachment":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media?parent=29217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/categories?post=29217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/tags?post=29217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}