{"id":28780,"date":"2020-09-22T16:00:40","date_gmt":"2020-09-22T14:00:40","guid":{"rendered":"https:\/\/www.irenemilito.it\/?p=28780"},"modified":"2020-09-21T17:17:05","modified_gmt":"2020-09-21T15:17:05","slug":"plumcake-con-chocolate-y-glaseado-de-limon","status":"publish","type":"post","link":"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/","title":{"rendered":"Plumcake con chocolate y glaseado de lim\u00f3n"},"content":{"rendered":"<p><strong>Ingredientes:<\/strong><\/p>\n<ul>\n<li>4 huevos<\/li>\n<li>100 g az\u00facar<\/li>\n<li>120 g harina<\/li>\n<li>1 cucharadita levadura seca<\/li>\n<li>200 g chocolate con leche<\/li>\n<li>20 g cacao en polvo<\/li>\n<li>Hojas menta<\/li>\n<li>200 g az\u00facar glas<\/li>\n<li>1 lim\u00f3n<\/li>\n<li>Mantequilla<\/li>\n<\/ul>\n<p><b>Preparaci\u00f3n:<\/b><\/p>\n<p>Funde el chocolate con leche al ba\u00f1o mar\u00eda, sin dejar de remover, y rellena con \u00e9l una manga pastelera con una boquilla muy fina y lisa. Forma con el chocolate pepitas sobre papel de hornear, t\u00e1palas con film y deja endurecer un ratito en la nevera. Bate los huevos con el az\u00facar hasta que doblen su volumen. Tamiza 100 g de harina con la levadura seca, y a\u00f1\u00e1delas, poco a poco con movimientos envolventes, a la masa. Incorpora la mitad de las pepitas a la masa y mezcla. Coloca esta masa en un molde rectangular, tipo plum cake, engrasado con mantequilla y enharinado, y cuece durante 45 minutos en el horno precalentado a 180\u00b0C. Retira y deja templar unos 5 minutos antes de desmoldar; luego deja enfriar del todo. Exprime el lim\u00f3n y filtra el zumo para eliminar las semillas. Coloca el az\u00facar glas en un cuenco y ve a\u00f1adiendo, poco a poco, el zumo, sin dejar de batir con varillas manuales hasta que consigas una crema blanca y espesa. Vierte despu\u00e9s el glaseado sobre el bizcocho y s\u00edrvelo espolvoreado con el resto de las pepitas de chocolate y con el cacao, y decorado con las hojitas de menta lavadas y secas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingredientes: 4 huevos 100 g az\u00facar 120 g harina 1 cucharadita levadura seca 200 g chocolate con leche 20 g cacao en polvo Hojas menta 200 g az\u00facar glas 1 lim\u00f3n Mantequilla Preparaci\u00f3n: Funde el chocolate con leche al ba\u00f1o mar\u00eda, sin dejar de remover, y rellena con \u00e9l una manga pastelera con una boquilla&#8230;<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/\">Read More<\/a><\/div>\n","protected":false},"author":3,"featured_media":28781,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3800],"tags":[],"class_list":["post-28780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plumcake con chocolate y glaseado de lim\u00f3n - IreneMilito.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plumcake con chocolate y glaseado de lim\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Ingredientes: 4 huevos 100 g az\u00facar 120 g harina 1 cucharadita levadura seca 200 g chocolate con leche 20 g cacao en polvo Hojas menta 200 g az\u00facar glas 1 lim\u00f3n Mantequilla Preparaci\u00f3n: Funde el chocolate con leche al ba\u00f1o mar\u00eda, sin dejar de remover, y rellena con \u00e9l una manga pastelera con una boquilla...Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/\" \/>\n<meta property=\"og:site_name\" content=\"IreneMilito.it\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-22T14:00:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-21T15:17:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/110842764_135226964900607_3027845371560507832_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Milito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Milito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/\",\"url\":\"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/\",\"name\":\"Plumcake con chocolate y glaseado de lim\u00f3n - IreneMilito.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/110842764_135226964900607_3027845371560507832_n.jpg\",\"datePublished\":\"2020-09-22T14:00:40+00:00\",\"dateModified\":\"2020-09-21T15:17:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/#primaryimage\",\"url\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/110842764_135226964900607_3027845371560507832_n.jpg\",\"contentUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/110842764_135226964900607_3027845371560507832_n.jpg\",\"width\":750,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.irenemilito.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plumcake con chocolate y glaseado de lim\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\",\"url\":\"https:\/\/www.irenemilito.it\/es\/\",\"name\":\"IreneMilito.it\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\",\"name\":\"Irene Milito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"caption\":\"Irene Milito\"},\"url\":\"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plumcake con chocolate y glaseado de lim\u00f3n - IreneMilito.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/","og_locale":"es_ES","og_type":"article","og_title":"Plumcake con chocolate y glaseado de lim\u00f3n","og_description":"Ingredientes: 4 huevos 100 g az\u00facar 120 g harina 1 cucharadita levadura seca 200 g chocolate con leche 20 g cacao en polvo Hojas menta 200 g az\u00facar glas 1 lim\u00f3n Mantequilla Preparaci\u00f3n: Funde el chocolate con leche al ba\u00f1o mar\u00eda, sin dejar de remover, y rellena con \u00e9l una manga pastelera con una boquilla...Read More","og_url":"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/","og_site_name":"IreneMilito.it","article_published_time":"2020-09-22T14:00:40+00:00","article_modified_time":"2020-09-21T15:17:05+00:00","og_image":[{"width":750,"height":750,"url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/110842764_135226964900607_3027845371560507832_n.jpg","type":"image\/jpeg"}],"author":"Irene Milito","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Irene Milito","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/","url":"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/","name":"Plumcake con chocolate y glaseado de lim\u00f3n - IreneMilito.it","isPartOf":{"@id":"https:\/\/www.irenemilito.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/#primaryimage"},"image":{"@id":"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/110842764_135226964900607_3027845371560507832_n.jpg","datePublished":"2020-09-22T14:00:40+00:00","dateModified":"2020-09-21T15:17:05+00:00","author":{"@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43"},"breadcrumb":{"@id":"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/#primaryimage","url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/110842764_135226964900607_3027845371560507832_n.jpg","contentUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/110842764_135226964900607_3027845371560507832_n.jpg","width":750,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/www.irenemilito.it\/es\/plumcake-con-chocolate-y-glaseado-de-limon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irenemilito.it\/es\/"},{"@type":"ListItem","position":2,"name":"Plumcake con chocolate y glaseado de lim\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.irenemilito.it\/es\/#website","url":"https:\/\/www.irenemilito.it\/es\/","name":"IreneMilito.it","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43","name":"Irene Milito","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","caption":"Irene Milito"},"url":"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/28780"}],"collection":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/comments?post=28780"}],"version-history":[{"count":1,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/28780\/revisions"}],"predecessor-version":[{"id":28785,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/28780\/revisions\/28785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media\/28781"}],"wp:attachment":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media?parent=28780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/categories?post=28780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/tags?post=28780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}