{"id":27599,"date":"2020-09-10T12:00:21","date_gmt":"2020-09-10T10:00:21","guid":{"rendered":"https:\/\/www.irenemilito.it\/?p=27599"},"modified":"2020-09-10T11:44:00","modified_gmt":"2020-09-10T09:44:00","slug":"postre-chocolatoso","status":"publish","type":"post","link":"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/","title":{"rendered":"Postre chocolatoso"},"content":{"rendered":"<p><strong>Ingredientes:<\/strong><\/p>\n<ul>\n<li>1 cucharada sopera de polvo para hornear<\/li>\n<li>1 taza de chocolate en polvo<span class=\"text_exposed_show\"><br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">2 tazas de harina<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">1 taza de az\u00facar<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">1 taza de leche<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">5 huevos<\/span><\/li>\n<\/ul>\n<p><strong>Ingredientes para el relleno e la cobertura:<\/strong><\/p>\n<ul>\n<li>3 cucharadas soperas de chocolate en polvo<\/li>\n<li>1 cucharada sopera de mantequilla<\/li>\n<li>Coco rallado o Chocolate granulado o Nueces picadas<\/li>\n<li>Chispas de chocolate al gusto para cubrir<\/li>\n<li>1 lata de crema de leche<\/li>\n<li>2 latas de leche condensada<\/li>\n<\/ul>\n<p><strong>Ingredientes para el jarabe:<\/strong><\/p>\n<ul>\n<li>2 cucharadas soperas de chocolate en polvo<\/li>\n<li>1 taza de leche<\/li>\n<li>1 taza de agua<\/li>\n<\/ul>\n<p><b>Preparaci\u00f3n:<\/b><\/p>\n<p>Batir las claras de huevo hasta que est\u00e9n r\u00edgidas, agregar las yemas de huevo una por una, el az\u00facar y continuar batiendo. Luego, la leche muy poco a poco, apaga y tamiza la harina y el chocolate sobre la masa y revuelve suavemente. Finalmente ponga la levadura y mezcle, la masa debe tomarse bien y parecer suave como espuma, as\u00ed que ponga la leche poco a poco para no perder el punto. Coloque en una sart\u00e9n de (aproximadamente 26&#215;33 cm o 30 cm de di\u00e1metro) engrasada y enharinada (si prefiere engrasar la sart\u00e9n y espolvorear chocolate en polvo, reemplazando la harina, para que el pastel est\u00e9 m\u00e1s oscuro). Hornee en un horno mediano durante aproximadamente 15 minutos dependiendo del horno. Llevar a fuego medio-bajo en una sart\u00e9n: leche condensada, chocolate en polvo y mantequilla hasta que salga de la sart\u00e9n (punto brigadeiro), espere a que se enfr\u00ede y agregue la crema gradualmente revolviendo hasta que est\u00e9 muy cremosa y f\u00e1cil de mezclar. Mezcle todo y cocine a fuego alto hasta que se reduja a la mitad. Cortar el pastel en 2 partes, remojar con el alm\u00edbar, llenar y cubrir con el relleno de brigadeiro. Espolvorea con coco rallado o nueces o chocolate granulado y sirve.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingredientes: 1 cucharada sopera de polvo para hornear 1 taza de chocolate en polvo 2 tazas de harina 1 taza de az\u00facar 1 taza de leche 5 huevos Ingredientes para el relleno e la cobertura: 3 cucharadas soperas de chocolate en polvo 1 cucharada sopera de mantequilla Coco rallado o Chocolate granulado o Nueces picadas&#8230;<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/\">Read More<\/a><\/div>\n","protected":false},"author":3,"featured_media":27600,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3800],"tags":[],"class_list":["post-27599","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Postre chocolatoso - IreneMilito.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Postre chocolatoso\" \/>\n<meta property=\"og:description\" content=\"Ingredientes: 1 cucharada sopera de polvo para hornear 1 taza de chocolate en polvo 2 tazas de harina 1 taza de az\u00facar 1 taza de leche 5 huevos Ingredientes para el relleno e la cobertura: 3 cucharadas soperas de chocolate en polvo 1 cucharada sopera de mantequilla Coco rallado o Chocolate granulado o Nueces picadas...Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/\" \/>\n<meta property=\"og:site_name\" content=\"IreneMilito.it\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-10T10:00:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-10T09:44:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95699619_109793600723522_1806876789918662656_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"945\" \/>\n\t<meta property=\"og:image:height\" content=\"945\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Milito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Milito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/\",\"url\":\"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/\",\"name\":\"Postre chocolatoso - IreneMilito.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95699619_109793600723522_1806876789918662656_n.jpg\",\"datePublished\":\"2020-09-10T10:00:21+00:00\",\"dateModified\":\"2020-09-10T09:44:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/#primaryimage\",\"url\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95699619_109793600723522_1806876789918662656_n.jpg\",\"contentUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95699619_109793600723522_1806876789918662656_n.jpg\",\"width\":945,\"height\":945},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.irenemilito.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Postre chocolatoso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\",\"url\":\"https:\/\/www.irenemilito.it\/es\/\",\"name\":\"IreneMilito.it\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\",\"name\":\"Irene Milito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"caption\":\"Irene Milito\"},\"url\":\"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Postre chocolatoso - IreneMilito.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/","og_locale":"es_ES","og_type":"article","og_title":"Postre chocolatoso","og_description":"Ingredientes: 1 cucharada sopera de polvo para hornear 1 taza de chocolate en polvo 2 tazas de harina 1 taza de az\u00facar 1 taza de leche 5 huevos Ingredientes para el relleno e la cobertura: 3 cucharadas soperas de chocolate en polvo 1 cucharada sopera de mantequilla Coco rallado o Chocolate granulado o Nueces picadas...Read More","og_url":"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/","og_site_name":"IreneMilito.it","article_published_time":"2020-09-10T10:00:21+00:00","article_modified_time":"2020-09-10T09:44:00+00:00","og_image":[{"width":945,"height":945,"url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95699619_109793600723522_1806876789918662656_n.jpg","type":"image\/jpeg"}],"author":"Irene Milito","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Irene Milito","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/","url":"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/","name":"Postre chocolatoso - IreneMilito.it","isPartOf":{"@id":"https:\/\/www.irenemilito.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/#primaryimage"},"image":{"@id":"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95699619_109793600723522_1806876789918662656_n.jpg","datePublished":"2020-09-10T10:00:21+00:00","dateModified":"2020-09-10T09:44:00+00:00","author":{"@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43"},"breadcrumb":{"@id":"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/#primaryimage","url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95699619_109793600723522_1806876789918662656_n.jpg","contentUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95699619_109793600723522_1806876789918662656_n.jpg","width":945,"height":945},{"@type":"BreadcrumbList","@id":"https:\/\/www.irenemilito.it\/es\/postre-chocolatoso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irenemilito.it\/es\/"},{"@type":"ListItem","position":2,"name":"Postre chocolatoso"}]},{"@type":"WebSite","@id":"https:\/\/www.irenemilito.it\/es\/#website","url":"https:\/\/www.irenemilito.it\/es\/","name":"IreneMilito.it","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43","name":"Irene Milito","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","caption":"Irene Milito"},"url":"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/27599"}],"collection":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/comments?post=27599"}],"version-history":[{"count":1,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/27599\/revisions"}],"predecessor-version":[{"id":27604,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/27599\/revisions\/27604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media\/27600"}],"wp:attachment":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media?parent=27599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/categories?post=27599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/tags?post=27599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}