{"id":27581,"date":"2020-09-10T09:00:28","date_gmt":"2020-09-10T07:00:28","guid":{"rendered":"https:\/\/www.irenemilito.it\/?p=27581"},"modified":"2020-09-09T19:15:03","modified_gmt":"2020-09-09T17:15:03","slug":"burritos-de-pollo","status":"publish","type":"post","link":"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/","title":{"rendered":"Burritos de pollo"},"content":{"rendered":"<p><strong>Ingredientes:<\/strong><\/p>\n<ul>\n<li>2 pechugas de pollo sin hueso<\/li>\n<li>\u00bd cebolla<span class=\"text_exposed_show\"><br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">\u00bd pimiento rojo<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">\u00bd pimiento verde<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">1 lim\u00f3n<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">1 aguacate<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">4 tortillas de trigo<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">Sazonador barbacoa<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">4 o 5 hojas de lechuga romana<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">Pimientos secos<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">Sal al gusto<\/span><\/li>\n<\/ul>\n<p><b>Preparaci\u00f3n<\/b><strong>:<\/strong><\/p>\n<div class=\"_xlr\">\n<div id=\"id_5f590ce16f6ac5458988916\" class=\"text_exposed_root text_exposed\"><span class=\"text_exposed_show\">Lo primero que debes hacer es preparar todos los ingredientes a utilizar como relleno del burrito. Para lograrlo pica la cebolla y el tomate en trozos peque\u00f1os. Seguidamente pica el pimiento verde y rojo en tiras. Pero si lo prefieres tambi\u00e9n los puedes picar en tiras como los dem\u00e1s ingredientes. Despu\u00e9s, pica el aguacate y res\u00e9rvalo dentro de un recipiente agreg\u00e1ndole un poco de zumo de lim\u00f3n y un poco de perejil picado. Para preparar el pollo, pica las pechugas de pollo en peque\u00f1as tiras y saz\u00f3nalas con un sabor a barbacoa, agreg\u00e1ndole las diferentes especias. Reserva por separado para que se fusionen los sabores dentro del pollo. Coge un recipiente y agr\u00e9gale un poco de aceite de oliva y empieza a sofre\u00edr la cebolla. Al tornarse transparente incorpora el tomate picado y deja que se cocine con la cebolla. Cuando la cebolla y el tomate est\u00e9n a medio hacer, deja caer las tiras de pollo y sazona de nuevo. Dale vueltas constantemente a la carne para que se pueda cocer por completo. A\u00f1ade los pimientos en tiras dentro de la sart\u00e9n junto a los dem\u00e1s ingredientes, para que se incorpore el sabor. Cuando la carne est\u00e9 casi lista, empieza a preparar las tortillas, sin dejar descuidado el pollo. Para lo cual, debes seguir las instrucciones que tienen en el empaque de las mismas. Puedes utilizar varias formas para calentarlas. Puedes hacerlo dentro de una sart\u00e9n, en el horno o el microondas. En esta ocasi\u00f3n se har\u00e1 uso del microondas por ser m\u00e1s r\u00e1pido, introd\u00facelas con papel film agujerado y en 60 segundos estar\u00e1n listas. Al tener listos todos los ingredientes, s\u00f3lo debes rellenar las tortillas y disfrutar de este platillo. Puedes seguir este orden, empieza colocando la lechuga, seguido del relleno de carne con verdura y finaliza con el aguacate que estaba reservado con el zumo de lim\u00f3n y el perejil picado.<\/span><\/div>\n<div id=\"fbPhotoSnowliftProductMiniListHscroll\" class=\"fbCommerceProductMiniListHscroll\"><\/div>\n<div id=\"fbPhotoSnowliftLegacyTagList\" class=\"pts fbPhotoLegacyTagList\">\n<div><\/div>\n<\/div>\n<div id=\"fbPhotoSnowliftCallToActionButton\" class=\"fbPhotosPhotoButtons\"><\/div>\n<div id=\"fbPhotoSnowliftPhotoFundraiser\"><\/div>\n<div id=\"fbPhotoSnowliftOwnerButtons\" class=\"mvm fbPhotosPhotoOwnerButtons stat_elem\"><\/div>\n<div id=\"fbPhotoSnowliftOriginalStory\" class=\"_56lj\"><\/div>\n<div id=\"fbPhotoSnowliftComputerVisionAnnotation\" class=\"fbPhotosPhotoCVAnnotation\"><\/div>\n<\/div>\n<div id=\"fbPhotoSnowliftVideoFundraiser\"><\/div>\n<div id=\"fbPhotoSnowliftGeneric Inform Treatments\" class=\"_98zx\"><\/div>\n<div id=\"fbPhotoSnowliftViews\" class=\"_4p3v\"><\/div>\n<form id=\"u_4_2\" class=\"fbPhotosSnowliftFeedbackForm commentable_item collapsible_comments\" action=\"https:\/\/www.facebook.com\/ajax\/ufi\/modify.php\" method=\"post\" data-ft=\"{&quot;tn&quot;:&quot;]&quot;}\">\n<div id=\"fbPhotoSnowliftFeedback\" class=\"fbPhotosSnowliftFeedback\"><\/div>\n<div>\n<div>\n<div class=\"_6iib\">\n<div class=\"_6iic\">\n<div class=\"_6iid\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/form>\n","protected":false},"excerpt":{"rendered":"<p>Ingredientes: 2 pechugas de pollo sin hueso \u00bd cebolla \u00bd pimiento rojo \u00bd pimiento verde 1 lim\u00f3n 1 aguacate 4 tortillas de trigo Sazonador barbacoa 4 o 5 hojas de lechuga romana Pimientos secos Sal al gusto Preparaci\u00f3n: Lo primero que debes hacer es preparar todos los ingredientes a utilizar como relleno del burrito. Para&#8230;<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/\">Read More<\/a><\/div>\n","protected":false},"author":3,"featured_media":27582,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3800],"tags":[],"class_list":["post-27581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Burritos de pollo - IreneMilito.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Burritos de pollo\" \/>\n<meta property=\"og:description\" content=\"Ingredientes: 2 pechugas de pollo sin hueso \u00bd cebolla \u00bd pimiento rojo \u00bd pimiento verde 1 lim\u00f3n 1 aguacate 4 tortillas de trigo Sazonador barbacoa 4 o 5 hojas de lechuga romana Pimientos secos Sal al gusto Preparaci\u00f3n: Lo primero que debes hacer es preparar todos los ingredientes a utilizar como relleno del burrito. Para...Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/\" \/>\n<meta property=\"og:site_name\" content=\"IreneMilito.it\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-10T07:00:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-09T17:15:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95427906_110897663946449_7516391844029136896_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"678\" \/>\n\t<meta property=\"og:image:height\" content=\"510\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Milito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Milito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/\",\"url\":\"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/\",\"name\":\"Burritos de pollo - IreneMilito.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95427906_110897663946449_7516391844029136896_n.jpg\",\"datePublished\":\"2020-09-10T07:00:28+00:00\",\"dateModified\":\"2020-09-09T17:15:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/#primaryimage\",\"url\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95427906_110897663946449_7516391844029136896_n.jpg\",\"contentUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95427906_110897663946449_7516391844029136896_n.jpg\",\"width\":678,\"height\":510},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.irenemilito.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Burritos de pollo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\",\"url\":\"https:\/\/www.irenemilito.it\/es\/\",\"name\":\"IreneMilito.it\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\",\"name\":\"Irene Milito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"caption\":\"Irene Milito\"},\"url\":\"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Burritos de pollo - IreneMilito.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/","og_locale":"es_ES","og_type":"article","og_title":"Burritos de pollo","og_description":"Ingredientes: 2 pechugas de pollo sin hueso \u00bd cebolla \u00bd pimiento rojo \u00bd pimiento verde 1 lim\u00f3n 1 aguacate 4 tortillas de trigo Sazonador barbacoa 4 o 5 hojas de lechuga romana Pimientos secos Sal al gusto Preparaci\u00f3n: Lo primero que debes hacer es preparar todos los ingredientes a utilizar como relleno del burrito. Para...Read More","og_url":"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/","og_site_name":"IreneMilito.it","article_published_time":"2020-09-10T07:00:28+00:00","article_modified_time":"2020-09-09T17:15:03+00:00","og_image":[{"width":678,"height":510,"url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95427906_110897663946449_7516391844029136896_n.jpg","type":"image\/jpeg"}],"author":"Irene Milito","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Irene Milito","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/","url":"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/","name":"Burritos de pollo - IreneMilito.it","isPartOf":{"@id":"https:\/\/www.irenemilito.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/#primaryimage"},"image":{"@id":"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95427906_110897663946449_7516391844029136896_n.jpg","datePublished":"2020-09-10T07:00:28+00:00","dateModified":"2020-09-09T17:15:03+00:00","author":{"@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43"},"breadcrumb":{"@id":"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/#primaryimage","url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95427906_110897663946449_7516391844029136896_n.jpg","contentUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/95427906_110897663946449_7516391844029136896_n.jpg","width":678,"height":510},{"@type":"BreadcrumbList","@id":"https:\/\/www.irenemilito.it\/es\/burritos-de-pollo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irenemilito.it\/es\/"},{"@type":"ListItem","position":2,"name":"Burritos de pollo"}]},{"@type":"WebSite","@id":"https:\/\/www.irenemilito.it\/es\/#website","url":"https:\/\/www.irenemilito.it\/es\/","name":"IreneMilito.it","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43","name":"Irene Milito","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","caption":"Irene Milito"},"url":"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/27581"}],"collection":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/comments?post=27581"}],"version-history":[{"count":1,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/27581\/revisions"}],"predecessor-version":[{"id":27586,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/27581\/revisions\/27586"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media\/27582"}],"wp:attachment":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media?parent=27581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/categories?post=27581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/tags?post=27581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}