{"id":27200,"date":"2020-09-07T12:00:24","date_gmt":"2020-09-07T10:00:24","guid":{"rendered":"https:\/\/www.irenemilito.it\/?p=27200"},"modified":"2020-09-07T10:22:06","modified_gmt":"2020-09-07T08:22:06","slug":"pastel-de-mantequilla-y-brownie","status":"publish","type":"post","link":"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/","title":{"rendered":"Pastel de mantequilla y brownie"},"content":{"rendered":"<p><strong>Ingredientes para el brownie:<\/strong><\/p>\n<ul>\n<li>140 gramos de chocolate negro (en pedazos)<span class=\"text_exposed_show\"><br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">50 gramos (\u00bc taza) de mantequilla sin sal<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">50 gramos (\u00bc taza) de az\u00facar morena<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">1 huevo<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">35 gramos (\u00bc taza) de harina<\/span><\/li>\n<\/ul>\n<p><b>Ingredientes para el pastel de mantequilla:<\/b><\/p>\n<ul>\n<li>120 gramos (\u00bd taza) de mantequilla sin sal<\/li>\n<li>100 gramos (\u00bd taza) de az\u00facar<\/li>\n<li>2 huevos<\/li>\n<li>120 gramos (1 taza) de harina<\/li>\n<li>\u00bc de cucharadita de polvo de hornear<\/li>\n<li>50 ml de leche<\/li>\n<\/ul>\n<p><b>Preparaci\u00f3n:<\/b><\/p>\n<p>Vamos a engrasar y forrar un molde rectangular de 10 cm x 20 cm para panqu\u00e9. Precalentamos el horno a 180\u00baC. Para hacer el brownie vamos a derretir el chocolate y la mantequilla a fuego lento. Lo retiramos del fuego una vez que est\u00e9 derretido y dejaremos enfriar un poco. Agregamos el az\u00facar morena hasta que se mezclen. Una vez fr\u00edo agregaremos el huevo y mezclamos bien. Incorporamos la harina, mezclamos hasta que est\u00e9n bien combinados. Vertemos la mezcla en el molde preparado y horneamos durante 15 minutos. Lo sacamos y ahora preparamos r\u00e1pidamente la masa para el pastel de mantequilla. Batimos la mantequilla con el az\u00facar hasta que quede cremoso. A\u00f1adimos los huevos, uno a la vez, batiendo bien despu\u00e9s de cada adici\u00f3n. Incorporamos la harina cernida y el polvo para hornear, a\u00f1adir lentamente la leche, y mezclamos hasta formar una masa consistente. Ahora verteremos la masa del pastel de mantequilla sobre el brownie precocido, y metemos al horno por 30 minutos o hasta que est\u00e9 perfectamente cocido que ser\u00e1 al momento de insertar un palillo en el centro y \u00e9ste salga limpio. Una vez listo, desmoldamos y dejamos enfriar.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingredientes para el brownie: 140 gramos de chocolate negro (en pedazos) 50 gramos (\u00bc taza) de mantequilla sin sal 50 gramos (\u00bc taza) de az\u00facar morena 1 huevo 35 gramos (\u00bc taza) de harina Ingredientes para el pastel de mantequilla: 120 gramos (\u00bd taza) de mantequilla sin sal 100 gramos (\u00bd taza) de az\u00facar 2&#8230;<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/\">Read More<\/a><\/div>\n","protected":false},"author":3,"featured_media":27201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3800],"tags":[],"class_list":["post-27200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pastel de mantequilla y brownie - IreneMilito.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pastel de mantequilla y brownie\" \/>\n<meta property=\"og:description\" content=\"Ingredientes para el brownie: 140 gramos de chocolate negro (en pedazos) 50 gramos (\u00bc taza) de mantequilla sin sal 50 gramos (\u00bc taza) de az\u00facar morena 1 huevo 35 gramos (\u00bc taza) de harina Ingredientes para el pastel de mantequilla: 120 gramos (\u00bd taza) de mantequilla sin sal 100 gramos (\u00bd taza) de az\u00facar 2...Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/\" \/>\n<meta property=\"og:site_name\" content=\"IreneMilito.it\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-07T10:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-07T08:22:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/101398131_127240938978788_473495740379824128_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Milito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Milito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/\",\"url\":\"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/\",\"name\":\"Pastel de mantequilla y brownie - IreneMilito.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/101398131_127240938978788_473495740379824128_n.jpg\",\"datePublished\":\"2020-09-07T10:00:24+00:00\",\"dateModified\":\"2020-09-07T08:22:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/#primaryimage\",\"url\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/101398131_127240938978788_473495740379824128_n.jpg\",\"contentUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/101398131_127240938978788_473495740379824128_n.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.irenemilito.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pastel de mantequilla y brownie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\",\"url\":\"https:\/\/www.irenemilito.it\/es\/\",\"name\":\"IreneMilito.it\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\",\"name\":\"Irene Milito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"caption\":\"Irene Milito\"},\"url\":\"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pastel de mantequilla y brownie - IreneMilito.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/","og_locale":"es_ES","og_type":"article","og_title":"Pastel de mantequilla y brownie","og_description":"Ingredientes para el brownie: 140 gramos de chocolate negro (en pedazos) 50 gramos (\u00bc taza) de mantequilla sin sal 50 gramos (\u00bc taza) de az\u00facar morena 1 huevo 35 gramos (\u00bc taza) de harina Ingredientes para el pastel de mantequilla: 120 gramos (\u00bd taza) de mantequilla sin sal 100 gramos (\u00bd taza) de az\u00facar 2...Read More","og_url":"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/","og_site_name":"IreneMilito.it","article_published_time":"2020-09-07T10:00:24+00:00","article_modified_time":"2020-09-07T08:22:06+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/101398131_127240938978788_473495740379824128_n.jpg","type":"image\/jpeg"}],"author":"Irene Milito","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Irene Milito","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/","url":"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/","name":"Pastel de mantequilla y brownie - IreneMilito.it","isPartOf":{"@id":"https:\/\/www.irenemilito.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/#primaryimage"},"image":{"@id":"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/101398131_127240938978788_473495740379824128_n.jpg","datePublished":"2020-09-07T10:00:24+00:00","dateModified":"2020-09-07T08:22:06+00:00","author":{"@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43"},"breadcrumb":{"@id":"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/#primaryimage","url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/101398131_127240938978788_473495740379824128_n.jpg","contentUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/101398131_127240938978788_473495740379824128_n.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.irenemilito.it\/es\/pastel-de-mantequilla-y-brownie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irenemilito.it\/es\/"},{"@type":"ListItem","position":2,"name":"Pastel de mantequilla y brownie"}]},{"@type":"WebSite","@id":"https:\/\/www.irenemilito.it\/es\/#website","url":"https:\/\/www.irenemilito.it\/es\/","name":"IreneMilito.it","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43","name":"Irene Milito","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","caption":"Irene Milito"},"url":"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/27200"}],"collection":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/comments?post=27200"}],"version-history":[{"count":1,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/27200\/revisions"}],"predecessor-version":[{"id":27205,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/27200\/revisions\/27205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media\/27201"}],"wp:attachment":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media?parent=27200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/categories?post=27200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/tags?post=27200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}