{"id":26602,"date":"2020-09-05T00:00:18","date_gmt":"2020-09-04T22:00:18","guid":{"rendered":"https:\/\/www.irenemilito.it\/?p=26602"},"modified":"2020-09-04T12:48:22","modified_gmt":"2020-09-04T10:48:22","slug":"budin-de-naranja","status":"publish","type":"post","link":"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/","title":{"rendered":"Bud\u00edn de naranja"},"content":{"rendered":"<p><strong>Ingredientes:<\/strong><\/p>\n<ul>\n<li>3 naranjas<\/li>\n<li>250 ml de leche<span class=\"text_exposed_show\"><br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">3 huevos<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">100 g az\u00facar<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">6 bizcochos<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">1 cucharadita de Brandy o ron<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">Caramelo l\u00edquido<\/span><\/li>\n<\/ul>\n<p><strong>Ingredientes para naranja confitada:<\/strong><\/p>\n<ul>\n<li>1 naranja<\/li>\n<li>300 ml de agua<\/li>\n<li>250 g de az\u00facar<\/li>\n<\/ul>\n<p><b>Preparaci\u00f3n:<\/b><\/p>\n<p>Yo he utilizado un molde de 22 cm. Pelamos las naranjas y les quitamos bien la piel blanca. Las ponemos en la batidora y trituramos bien hasta obtener un pur\u00e9. Mezclar el pur\u00e9 con los huevos y el az\u00facar, y batir hasta que quede bien incorporado. Desmenuzar los bizcochos en un taz\u00f3n. Regarlos con la leche caliente y agregar la preparaci\u00f3n anterior. Ba\u00f1ar con el licor, remover y dejar reposar la masa 2 o 3 minutos. Precalentar el horno a 150\u00baC. Engrasar con aceite el molde, poner el caramelo l\u00edquido extendido en la base. Agregar la masa y cocerla a ba\u00f1o Mar\u00eda 40 minutos (seg\u00fan el horno). Lo sacamos y dejamos enfriar y luego lo pasamos a la nevera. Naranja confitada: Ponemos en un recipiente amplio a calentar 300 ml de agua con el az\u00facar hasta fundirlo. Lavar la naranja y cortarla en rodajas y agregarla al alm\u00edbar. Confitarlas 30 minutos a fuego lento con el recipiente tapado (de ser posible con tapa de cristal para que vayamos viendo). Luego las dejamos escurrir sobre una rejilla y sobre papel vegetal untado con un poquito de aceite o mantequilla para que no se peguen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingredientes: 3 naranjas 250 ml de leche 3 huevos 100 g az\u00facar 6 bizcochos 1 cucharadita de Brandy o ron Caramelo l\u00edquido Ingredientes para naranja confitada: 1 naranja 300 ml de agua 250 g de az\u00facar Preparaci\u00f3n: Yo he utilizado un molde de 22 cm. Pelamos las naranjas y les quitamos bien la piel blanca&#8230;.<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/\">Read More<\/a><\/div>\n","protected":false},"author":3,"featured_media":26603,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3800],"tags":[],"class_list":["post-26602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bud\u00edn de naranja - IreneMilito.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bud\u00edn de naranja\" \/>\n<meta property=\"og:description\" content=\"Ingredientes: 3 naranjas 250 ml de leche 3 huevos 100 g az\u00facar 6 bizcochos 1 cucharadita de Brandy o ron Caramelo l\u00edquido Ingredientes para naranja confitada: 1 naranja 300 ml de agua 250 g de az\u00facar Preparaci\u00f3n: Yo he utilizado un molde de 22 cm. Pelamos las naranjas y les quitamos bien la piel blanca....Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/\" \/>\n<meta property=\"og:site_name\" content=\"IreneMilito.it\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-04T22:00:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-04T10:48:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100875832_130016382034577_1422473454535311360_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Milito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Milito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/\",\"url\":\"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/\",\"name\":\"Bud\u00edn de naranja - IreneMilito.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100875832_130016382034577_1422473454535311360_n.jpg\",\"datePublished\":\"2020-09-04T22:00:18+00:00\",\"dateModified\":\"2020-09-04T10:48:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/#primaryimage\",\"url\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100875832_130016382034577_1422473454535311360_n.jpg\",\"contentUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100875832_130016382034577_1422473454535311360_n.jpg\",\"width\":580,\"height\":580},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.irenemilito.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bud\u00edn de naranja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\",\"url\":\"https:\/\/www.irenemilito.it\/es\/\",\"name\":\"IreneMilito.it\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\",\"name\":\"Irene Milito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"caption\":\"Irene Milito\"},\"url\":\"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bud\u00edn de naranja - IreneMilito.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/","og_locale":"es_ES","og_type":"article","og_title":"Bud\u00edn de naranja","og_description":"Ingredientes: 3 naranjas 250 ml de leche 3 huevos 100 g az\u00facar 6 bizcochos 1 cucharadita de Brandy o ron Caramelo l\u00edquido Ingredientes para naranja confitada: 1 naranja 300 ml de agua 250 g de az\u00facar Preparaci\u00f3n: Yo he utilizado un molde de 22 cm. Pelamos las naranjas y les quitamos bien la piel blanca....Read More","og_url":"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/","og_site_name":"IreneMilito.it","article_published_time":"2020-09-04T22:00:18+00:00","article_modified_time":"2020-09-04T10:48:22+00:00","og_image":[{"width":580,"height":580,"url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100875832_130016382034577_1422473454535311360_n.jpg","type":"image\/jpeg"}],"author":"Irene Milito","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Irene Milito","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/","url":"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/","name":"Bud\u00edn de naranja - IreneMilito.it","isPartOf":{"@id":"https:\/\/www.irenemilito.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/#primaryimage"},"image":{"@id":"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100875832_130016382034577_1422473454535311360_n.jpg","datePublished":"2020-09-04T22:00:18+00:00","dateModified":"2020-09-04T10:48:22+00:00","author":{"@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43"},"breadcrumb":{"@id":"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/#primaryimage","url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100875832_130016382034577_1422473454535311360_n.jpg","contentUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100875832_130016382034577_1422473454535311360_n.jpg","width":580,"height":580},{"@type":"BreadcrumbList","@id":"https:\/\/www.irenemilito.it\/es\/budin-de-naranja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irenemilito.it\/es\/"},{"@type":"ListItem","position":2,"name":"Bud\u00edn de naranja"}]},{"@type":"WebSite","@id":"https:\/\/www.irenemilito.it\/es\/#website","url":"https:\/\/www.irenemilito.it\/es\/","name":"IreneMilito.it","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43","name":"Irene Milito","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","caption":"Irene Milito"},"url":"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/26602"}],"collection":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/comments?post=26602"}],"version-history":[{"count":1,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/26602\/revisions"}],"predecessor-version":[{"id":26607,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/26602\/revisions\/26607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media\/26603"}],"wp:attachment":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media?parent=26602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/categories?post=26602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/tags?post=26602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}