{"id":26584,"date":"2020-09-04T21:30:51","date_gmt":"2020-09-04T19:30:51","guid":{"rendered":"https:\/\/www.irenemilito.it\/?p=26584"},"modified":"2020-09-04T12:04:50","modified_gmt":"2020-09-04T10:04:50","slug":"pastel-de-papa-con-carne","status":"publish","type":"post","link":"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/","title":{"rendered":"Pastel de papa con carne"},"content":{"rendered":"<p><strong>Ingredientes:<\/strong><\/p>\n<ul>\n<li>1500 g de carne molida<\/li>\n<li>1 cebolla<span class=\"text_exposed_show\"><br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">3 dientes de ajo<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">Aceite de oliva<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">2 cucharadas de perejil picado<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">\u00bd cucharadita de piment\u00f3n dulce<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">1 pizca de comino<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">1 pizca de pimienta negra molida<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">1 pizca de sal<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">150 ml de vino blanco<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">4 cucharadas de tomate frito<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">1 pastilla de caldo de res<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">400 ml de agua<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">20 g de harina de trigo<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">20 g de mantequilla sin sal<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">350 ml de leche<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">5 papas (tama\u00f1o mediano)<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">1 l\u00e1mina 230 g de masa quebrada en forma circular<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">Tomates Cherry al gusto<br \/>\n<\/span><\/li>\n<li><span class=\"text_exposed_show\">200 g de mezcla de 4 quesos rallados<\/span><\/li>\n<\/ul>\n<p><b>Preparaci\u00f3n:<\/b><\/p>\n<p>Para elaborar esta receta necesitar\u00e1s un molde circular desmontable para bizcochos o un molde desechable de aluminio.<br \/>\nComienza haciendo la carne. Pon el agua a calentar 2 minutos en el microondas a potencia m\u00e1xima, seguido agrega dentro la pastilla de caldo de res, remueve con una cuchara hasta que se disuelva y reserva para usarlo m\u00e1s adelante. Corta la cebolla y los ajos, a\u00f1\u00e1delos a una sart\u00e9n grande o una cazuela a fuego medio con 1 cucharada de aceite, deja sofre\u00edr durante 6 minutos removiendo de vez en cuando. Agrega la carne, piment\u00f3n dulce, pimienta negra, comino, perejil picado, sal, revuelve y deja sofre\u00edr 4 minutos. Contin\u00faa a\u00f1adiendo el vino blanco y tomate frito, y deja cocinar 5 minutos. Agrega el agua con el caldo, remueve y deja cocinar durante 30 minutos. Mientras, pela y corta las papas en rodajas finas, (con medio cent\u00edmetro de grosor aproximadamente). Ponlas a fre\u00edr en aceite caliente a fuego medio durante 10 minutos (deben estar semi blandas), ret\u00edralas del aceite, ponlas a escurrir sobre papel de cocina en un plato y a\u00f1\u00e1deles sal por encima. Saca la masa quebrada de la nevera, desenr\u00f3llala y col\u00f3cala con el papel dentro del molde. Presiona con las manos, hasta que se asiente en el fondo y despu\u00e9s con los dedos presiona todo el borde hasta que quede liso (sin dobleces). Agrega dentro las papas y rep\u00e1rtelas bien, a\u00f1ade encima la carne molida y rep\u00e1rtela (no la hemos usado toda, ten en cuenta que debes dejar espacio encima para la bechamel y el queso). En este paso haz la bechamel, te damos la clave para hacerla f\u00e1cil y sin grumos. Mezcla en una copa la harina y la leche en fr\u00edo, remueve hasta que se disuelva la harina, lleva la leche al microondas a potencia m\u00e1xima durante 40 segundos (no te puedes pasar de ese tiempo). Pon una sart\u00e9n a fuego medio bajo, coloca la mantequilla, cuando est\u00e9 fundida a\u00f1ade la leche, pimienta, sal y remueve con unas varillas haciendo c\u00edrculos 4 minutos hasta que veas que se espesa. A\u00f1\u00e1dela sobre la carne del pastel, agrega por encima el queso rallado, corta los tomates Cherry a la mitad y col\u00f3calos sobre el queso a tu gusto. Precalienta el horno a 200\u00baC con calor por debajo, coloca el molde con el pastel de papas y carne, d\u00e9jalo 20 minutos y ret\u00edralo. Deja enfriar 10 minutos y estar\u00e1 listo para disfrutarlo. Si gustas puedes a\u00f1adir perejil picado encima.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingredientes: 1500 g de carne molida 1 cebolla 3 dientes de ajo Aceite de oliva 2 cucharadas de perejil picado \u00bd cucharadita de piment\u00f3n dulce 1 pizca de comino 1 pizca de pimienta negra molida 1 pizca de sal 150 ml de vino blanco 4 cucharadas de tomate frito 1 pastilla de caldo de res&#8230;<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/\">Read More<\/a><\/div>\n","protected":false},"author":3,"featured_media":26585,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3800],"tags":[],"class_list":["post-26584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pastel de papa con carne - IreneMilito.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pastel de papa con carne\" \/>\n<meta property=\"og:description\" content=\"Ingredientes: 1500 g de carne molida 1 cebolla 3 dientes de ajo Aceite de oliva 2 cucharadas de perejil picado \u00bd cucharadita de piment\u00f3n dulce 1 pizca de comino 1 pizca de pimienta negra molida 1 pizca de sal 150 ml de vino blanco 4 cucharadas de tomate frito 1 pastilla de caldo de res...Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/\" \/>\n<meta property=\"og:site_name\" content=\"IreneMilito.it\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-04T19:30:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-04T10:04:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100935279_130037502032465_3070852769976942592_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Milito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Milito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/\",\"url\":\"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/\",\"name\":\"Pastel de papa con carne - IreneMilito.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100935279_130037502032465_3070852769976942592_n.jpg\",\"datePublished\":\"2020-09-04T19:30:51+00:00\",\"dateModified\":\"2020-09-04T10:04:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/#primaryimage\",\"url\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100935279_130037502032465_3070852769976942592_n.jpg\",\"contentUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100935279_130037502032465_3070852769976942592_n.jpg\",\"width\":720,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.irenemilito.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pastel de papa con carne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\",\"url\":\"https:\/\/www.irenemilito.it\/es\/\",\"name\":\"IreneMilito.it\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\",\"name\":\"Irene Milito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"caption\":\"Irene Milito\"},\"url\":\"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pastel de papa con carne - IreneMilito.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/","og_locale":"es_ES","og_type":"article","og_title":"Pastel de papa con carne","og_description":"Ingredientes: 1500 g de carne molida 1 cebolla 3 dientes de ajo Aceite de oliva 2 cucharadas de perejil picado \u00bd cucharadita de piment\u00f3n dulce 1 pizca de comino 1 pizca de pimienta negra molida 1 pizca de sal 150 ml de vino blanco 4 cucharadas de tomate frito 1 pastilla de caldo de res...Read More","og_url":"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/","og_site_name":"IreneMilito.it","article_published_time":"2020-09-04T19:30:51+00:00","article_modified_time":"2020-09-04T10:04:50+00:00","og_image":[{"width":720,"height":540,"url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100935279_130037502032465_3070852769976942592_n.jpg","type":"image\/jpeg"}],"author":"Irene Milito","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Irene Milito","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/","url":"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/","name":"Pastel de papa con carne - IreneMilito.it","isPartOf":{"@id":"https:\/\/www.irenemilito.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/#primaryimage"},"image":{"@id":"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100935279_130037502032465_3070852769976942592_n.jpg","datePublished":"2020-09-04T19:30:51+00:00","dateModified":"2020-09-04T10:04:50+00:00","author":{"@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43"},"breadcrumb":{"@id":"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/#primaryimage","url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100935279_130037502032465_3070852769976942592_n.jpg","contentUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/100935279_130037502032465_3070852769976942592_n.jpg","width":720,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.irenemilito.it\/es\/pastel-de-papa-con-carne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irenemilito.it\/es\/"},{"@type":"ListItem","position":2,"name":"Pastel de papa con carne"}]},{"@type":"WebSite","@id":"https:\/\/www.irenemilito.it\/es\/#website","url":"https:\/\/www.irenemilito.it\/es\/","name":"IreneMilito.it","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43","name":"Irene Milito","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","caption":"Irene Milito"},"url":"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/26584"}],"collection":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/comments?post=26584"}],"version-history":[{"count":1,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/26584\/revisions"}],"predecessor-version":[{"id":26589,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/26584\/revisions\/26589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media\/26585"}],"wp:attachment":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media?parent=26584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/categories?post=26584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/tags?post=26584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}