{"id":26425,"date":"2020-09-04T11:30:16","date_gmt":"2020-09-04T09:30:16","guid":{"rendered":"https:\/\/www.irenemilito.it\/?p=26425"},"modified":"2020-09-03T17:27:41","modified_gmt":"2020-09-03T15:27:41","slug":"costillas-de-cerdo-al-horno-con-papas","status":"publish","type":"post","link":"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/","title":{"rendered":"Costillas de cerdo al horno con papas"},"content":{"rendered":"<p><strong>Ingredientes:<\/strong><\/p>\n<ul>\n<li>1 y 1\/2 kg de costillas de cerdo<\/li>\n<li>750 g de papas<\/li>\n<li>2 cebollas medianas<\/li>\n<li>4 dientes de ajo<\/li>\n<li>Sal<\/li>\n<li>Aceite de oliva<\/li>\n<li>Pimienta negra<\/li>\n<li>1 pastilla de caldo de carne<\/li>\n<li>Perejil picado<\/li>\n<li>200 ml de vino blanco<\/li>\n<\/ul>\n<p><b>Preparaci\u00f3n:<\/b><\/p>\n<p>Comenzaremos limpiando las costillas, y si las vas a hacer ya cortadas, es el momento de hacerlo, aunque es m\u00e1s c\u00f3modo hornear el costillar o costillares completos y cortarlas despu\u00e9s, sobre todo a la hora de dar la vuelta a las costillas. Cuando las laves bien, deja que se sequen mientras preparamos el resto de los ingredientes. Es buen momento para poner ya el horno a calentar a 200\u00baC, tanto por arriba como por debajo. Pelamos las papas, las lavamos y las cortamos en rodajas, que usaremos como cama para las costillas, junto con las cebollas, que pelaremos y cortaremos en juliana, en trozos grandes. Tomamos la bandeja del horno y echamos un poco de aceite de oliva en el fondo y lo refregamos bien por toda la bandeja, y colocamos las papas y luego las cebollas. En la licuadora vamos a echar los ajos pelados, perejil picado al gusto, el vino blanco, un poco de sal y pimienta negra, un chorrito de aceite de oliva y una pastilla de caldo de carne, y batimos todo hasta conseguir una mezcla homog\u00e9nea, que ser\u00e1 m\u00e1s bien espesita. Con ella vamos a embadurnar bien las costillas por todos lados y las colocamos sobre la cama de papa y cebolla. Cuando el horno alcance la temperatura que queremos, metemos la bandeja con nuestros ingredientes y dejamos hornear bien por ambos lados. El tiempo de horneado depender\u00e1 del grosor de las costillas, por lo que tenemos que ir viendo cuando est\u00e1n doradas por un lado para darles la vuelta y hornearlas por el otro lado. Antes de sacarlas es recomendable darles un \u00faltimo toque de grill durante unos minutos, para que acaben de dorarse bien por ambos lados, y cuando est\u00e9n en su punto, las sacamos y las servimos. Sirve el trozo de costilla para cada comensal junto con un poco de la guarnici\u00f3n de cebolla y papa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingredientes: 1 y 1\/2 kg de costillas de cerdo 750 g de papas 2 cebollas medianas 4 dientes de ajo Sal Aceite de oliva Pimienta negra 1 pastilla de caldo de carne Perejil picado 200 ml de vino blanco Preparaci\u00f3n: Comenzaremos limpiando las costillas, y si las vas a hacer ya cortadas, es el momento&#8230;<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/\">Read More<\/a><\/div>\n","protected":false},"author":3,"featured_media":26426,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3800],"tags":[],"class_list":["post-26425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Costillas de cerdo al horno con papas - IreneMilito.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Costillas de cerdo al horno con papas\" \/>\n<meta property=\"og:description\" content=\"Ingredientes: 1 y 1\/2 kg de costillas de cerdo 750 g de papas 2 cebollas medianas 4 dientes de ajo Sal Aceite de oliva Pimienta negra 1 pastilla de caldo de carne Perejil picado 200 ml de vino blanco Preparaci\u00f3n: Comenzaremos limpiando las costillas, y si las vas a hacer ya cortadas, es el momento...Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/\" \/>\n<meta property=\"og:site_name\" content=\"IreneMilito.it\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-04T09:30:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-03T15:27:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/108089845_147583656944516_1700514635830490480_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"504\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Milito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Milito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/\",\"url\":\"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/\",\"name\":\"Costillas de cerdo al horno con papas - IreneMilito.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/108089845_147583656944516_1700514635830490480_n.jpg\",\"datePublished\":\"2020-09-04T09:30:16+00:00\",\"dateModified\":\"2020-09-03T15:27:41+00:00\",\"author\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/#primaryimage\",\"url\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/108089845_147583656944516_1700514635830490480_n.jpg\",\"contentUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/108089845_147583656944516_1700514635830490480_n.jpg\",\"width\":960,\"height\":504},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.irenemilito.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Costillas de cerdo al horno con papas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\",\"url\":\"https:\/\/www.irenemilito.it\/es\/\",\"name\":\"IreneMilito.it\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\",\"name\":\"Irene Milito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"caption\":\"Irene Milito\"},\"url\":\"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Costillas de cerdo al horno con papas - IreneMilito.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/","og_locale":"es_ES","og_type":"article","og_title":"Costillas de cerdo al horno con papas","og_description":"Ingredientes: 1 y 1\/2 kg de costillas de cerdo 750 g de papas 2 cebollas medianas 4 dientes de ajo Sal Aceite de oliva Pimienta negra 1 pastilla de caldo de carne Perejil picado 200 ml de vino blanco Preparaci\u00f3n: Comenzaremos limpiando las costillas, y si las vas a hacer ya cortadas, es el momento...Read More","og_url":"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/","og_site_name":"IreneMilito.it","article_published_time":"2020-09-04T09:30:16+00:00","article_modified_time":"2020-09-03T15:27:41+00:00","og_image":[{"width":960,"height":504,"url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/108089845_147583656944516_1700514635830490480_n.jpg","type":"image\/jpeg"}],"author":"Irene Milito","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Irene Milito","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/","url":"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/","name":"Costillas de cerdo al horno con papas - IreneMilito.it","isPartOf":{"@id":"https:\/\/www.irenemilito.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/#primaryimage"},"image":{"@id":"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/108089845_147583656944516_1700514635830490480_n.jpg","datePublished":"2020-09-04T09:30:16+00:00","dateModified":"2020-09-03T15:27:41+00:00","author":{"@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43"},"breadcrumb":{"@id":"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/#primaryimage","url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/108089845_147583656944516_1700514635830490480_n.jpg","contentUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/09\/108089845_147583656944516_1700514635830490480_n.jpg","width":960,"height":504},{"@type":"BreadcrumbList","@id":"https:\/\/www.irenemilito.it\/es\/costillas-de-cerdo-al-horno-con-papas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irenemilito.it\/es\/"},{"@type":"ListItem","position":2,"name":"Costillas de cerdo al horno con papas"}]},{"@type":"WebSite","@id":"https:\/\/www.irenemilito.it\/es\/#website","url":"https:\/\/www.irenemilito.it\/es\/","name":"IreneMilito.it","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43","name":"Irene Milito","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","caption":"Irene Milito"},"url":"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/26425"}],"collection":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/comments?post=26425"}],"version-history":[{"count":1,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/26425\/revisions"}],"predecessor-version":[{"id":26430,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/26425\/revisions\/26430"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media\/26426"}],"wp:attachment":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media?parent=26425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/categories?post=26425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/tags?post=26425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}