{"id":26103,"date":"2020-08-30T15:00:38","date_gmt":"2020-08-30T13:00:38","guid":{"rendered":"https:\/\/www.irenemilito.it\/?p=26103"},"modified":"2020-08-29T18:34:25","modified_gmt":"2020-08-29T16:34:25","slug":"cocina-italiana-calabacin-frito-con-menta","status":"publish","type":"post","link":"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/","title":{"rendered":"Cocina italiana: Calabac\u00edn frito con menta"},"content":{"rendered":"<p><b>Tiempo de preparaci\u00f3n: <\/b>30 minutos aproximadamente (m\u00e1s el tiempo de cocci\u00f3n)<\/p>\n<p><strong>Porciones:\u00a0<\/strong>4 personas<\/p>\n<p><strong>Ingredientes:<\/strong><\/p>\n<ul>\n<li>4 calabacines<\/li>\n<li>2 chalotes<\/li>\n<li>2 dientes de ajo<\/li>\n<li>2 cucharadas de harina<\/li>\n<li>4 cucharadas de aceite de oliva<\/li>\n<li>1 pu\u00f1ado de meta<\/li>\n<li>1 manojo de perejil liso<\/li>\n<li>400 g de tomates (en conserva)<\/li>\n<li>El zumo de 1 lim\u00f3n<\/li>\n<li>2 cucharadas de pan rallado<\/li>\n<li>2 cucharadas de pecorino reci\u00e9n rallado<\/li>\n<li>Sal<\/li>\n<li>Pimienta<\/li>\n<\/ul>\n<p><b>Preparaci\u00f3n:<\/b><\/p>\n<p>Precaliente el horno a 200\u00b0C. Limpie, lave y corte los calabacines en rodajas. Pele los chalotes y el ajo, y p\u00edquelos. Eche la harina en un plato y reboce en ella las rodajas de calabac\u00edn. Caliente 2 cucharadas de aceite en una sart\u00e9n y dore en \u00e9l las rodajas de calabac\u00edn. S\u00e1quelas y res\u00e9rvelas. Lave las hierbas arom\u00e1ticas, sac\u00fadales el agua y p\u00edquelas. Eche el resto del aceite en la sart\u00e9n y rehogue los chalotes, el ajo y los tomates con el zumo y las hierbas arom\u00e1ticas (use solo la mitad del perejil). Despu\u00e9s de unos 3 minutos salpimiente bien y aparte la sart\u00e9n del fuego. Engrase un molde. Coloque en \u00e9l la mitad de las rodajas de calabac\u00edn. Roc\u00edelas con un poco de zumo de lim\u00f3n. C\u00fabralas con la mezcla de la sart\u00e9n y ponga encima las dem\u00e1s rodajas de calabac\u00edn. Vierta por encima el resto del zumo de lim\u00f3n. Mezcle el pan rallado y el queso, y espolvoree la verdura con esta mezcla. Gratine en el horno durante unos 20 minutos. Sirva espolvoreado con el perejil restante.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tiempo de preparaci\u00f3n: 30 minutos aproximadamente (m\u00e1s el tiempo de cocci\u00f3n) Porciones:\u00a04 personas Ingredientes: 4 calabacines 2 chalotes 2 dientes de ajo 2 cucharadas de harina 4 cucharadas de aceite de oliva 1 pu\u00f1ado de meta 1 manojo de perejil liso 400 g de tomates (en conserva) El zumo de 1 lim\u00f3n 2 cucharadas de&#8230;<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/\">Read More<\/a><\/div>\n","protected":false},"author":3,"featured_media":26104,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[15158],"tags":[],"class_list":["post-26103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cocina-italiana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cocina italiana: Calabac\u00edn frito con menta - IreneMilito.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cocina italiana: Calabac\u00edn frito con menta\" \/>\n<meta property=\"og:description\" content=\"Tiempo de preparaci\u00f3n: 30 minutos aproximadamente (m\u00e1s el tiempo de cocci\u00f3n) Porciones:\u00a04 personas Ingredientes: 4 calabacines 2 chalotes 2 dientes de ajo 2 cucharadas de harina 4 cucharadas de aceite de oliva 1 pu\u00f1ado de meta 1 manojo de perejil liso 400 g de tomates (en conserva) El zumo de 1 lim\u00f3n 2 cucharadas de...Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/\" \/>\n<meta property=\"og:site_name\" content=\"IreneMilito.it\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-30T13:00:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-29T16:34:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/08\/download-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Milito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Milito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/\",\"url\":\"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/\",\"name\":\"Cocina italiana: Calabac\u00edn frito con menta - IreneMilito.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/08\/download-1.jpeg\",\"datePublished\":\"2020-08-30T13:00:38+00:00\",\"dateModified\":\"2020-08-29T16:34:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/#primaryimage\",\"url\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/08\/download-1.jpeg\",\"contentUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/08\/download-1.jpeg\",\"width\":300,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.irenemilito.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cocina italiana: Calabac\u00edn frito con menta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\",\"url\":\"https:\/\/www.irenemilito.it\/es\/\",\"name\":\"IreneMilito.it\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\",\"name\":\"Irene Milito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"caption\":\"Irene Milito\"},\"url\":\"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cocina italiana: Calabac\u00edn frito con menta - IreneMilito.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/","og_locale":"es_ES","og_type":"article","og_title":"Cocina italiana: Calabac\u00edn frito con menta","og_description":"Tiempo de preparaci\u00f3n: 30 minutos aproximadamente (m\u00e1s el tiempo de cocci\u00f3n) Porciones:\u00a04 personas Ingredientes: 4 calabacines 2 chalotes 2 dientes de ajo 2 cucharadas de harina 4 cucharadas de aceite de oliva 1 pu\u00f1ado de meta 1 manojo de perejil liso 400 g de tomates (en conserva) El zumo de 1 lim\u00f3n 2 cucharadas de...Read More","og_url":"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/","og_site_name":"IreneMilito.it","article_published_time":"2020-08-30T13:00:38+00:00","article_modified_time":"2020-08-29T16:34:25+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/08\/download-1.jpeg","type":"image\/jpeg"}],"author":"Irene Milito","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Irene Milito","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/","url":"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/","name":"Cocina italiana: Calabac\u00edn frito con menta - IreneMilito.it","isPartOf":{"@id":"https:\/\/www.irenemilito.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/#primaryimage"},"image":{"@id":"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/08\/download-1.jpeg","datePublished":"2020-08-30T13:00:38+00:00","dateModified":"2020-08-29T16:34:25+00:00","author":{"@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43"},"breadcrumb":{"@id":"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/#primaryimage","url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/08\/download-1.jpeg","contentUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2020\/08\/download-1.jpeg","width":300,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/www.irenemilito.it\/es\/cocina-italiana-calabacin-frito-con-menta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irenemilito.it\/es\/"},{"@type":"ListItem","position":2,"name":"Cocina italiana: Calabac\u00edn frito con menta"}]},{"@type":"WebSite","@id":"https:\/\/www.irenemilito.it\/es\/#website","url":"https:\/\/www.irenemilito.it\/es\/","name":"IreneMilito.it","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43","name":"Irene Milito","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","caption":"Irene Milito"},"url":"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/26103"}],"collection":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/comments?post=26103"}],"version-history":[{"count":1,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/26103\/revisions"}],"predecessor-version":[{"id":26108,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/26103\/revisions\/26108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media\/26104"}],"wp:attachment":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media?parent=26103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/categories?post=26103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/tags?post=26103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}