{"id":19212,"date":"2019-02-24T17:19:58","date_gmt":"2019-02-24T16:19:58","guid":{"rendered":"https:\/\/www.irenemilito.it\/?p=19212"},"modified":"2019-02-24T17:19:58","modified_gmt":"2019-02-24T16:19:58","slug":"pastel-hojaldre-liviano-de-zucchinis","status":"publish","type":"post","link":"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/","title":{"rendered":"Pastel hojaldre liviano de zucchinis"},"content":{"rendered":"<p><strong>Ingredientes:<\/strong><\/p>\n<ul>\n<li>1 disco de masa hojaldre (para tarta)<\/li>\n<li>1 cucharada de mantequilla<\/li>\n<li>4 zucchinis medianos, picado<\/li>\n<li>3 huevos<\/li>\n<li>2 cucharaditas de queso crema<\/li>\n<li>4 cucharadas de reques\u00f3n (ricotta)<\/li>\n<li>50 g de queso Cheddar, rallado<\/li>\n<li>Sal<\/li>\n<li>Pimienta<\/li>\n<\/ul>\n<p><b>Preparaci\u00f3n:<\/b><\/p>\n<p>Precalentar el horno a 220\u00b0C (horno bien caliente). Enmantecar y enharinar una tartera con el disco de masa y reservar. En una sart\u00e9n, calentar la mantequilla y cocinar los zucchinis hasta que esten ligeramente dorados y tiernos. Colocar sobre la masa. En un bol, batir juntos los huevos, el queso crema, el reques\u00f3n y el queso Cheddar. Condimentar bien con sal y pimienta. Verter en la tartera y extender. Llevar al horno. Cocinar 30 minutos o hasta que est\u00e9 dorada y ligeramente firme. Servir tibia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingredientes: 1 disco de masa hojaldre (para tarta) 1 cucharada de mantequilla 4 zucchinis medianos, picado 3 huevos 2 cucharaditas de queso crema 4 cucharadas de reques\u00f3n (ricotta) 50 g de queso Cheddar, rallado Sal Pimienta Preparaci\u00f3n: Precalentar el horno a 220\u00b0C (horno bien caliente). Enmantecar y enharinar una tartera con el disco de masa&#8230;<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/\">Read More<\/a><\/div>\n","protected":false},"author":3,"featured_media":19213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3800],"tags":[4060,3943,2934,5575,2863,7682,8120,5903,3833,3875,5425],"class_list":["post-19212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas","tag-queso-cheddar","tag-queso-crema","tag-recetas-con-el-queso","tag-recetas-con-el-queso-italiano","tag-recetas-con-la-verdura","tag-recetas-con-las-zucchinis","tag-recetas-de-pasteles-hojaldres","tag-recetas-livianas","tag-recetas-saladas","tag-requeson-ricotta","tag-zucchinis-medianos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pastel hojaldre liviano de zucchinis - IreneMilito.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pastel hojaldre liviano de zucchinis\" \/>\n<meta property=\"og:description\" content=\"Ingredientes: 1 disco de masa hojaldre (para tarta) 1 cucharada de mantequilla 4 zucchinis medianos, picado 3 huevos 2 cucharaditas de queso crema 4 cucharadas de reques\u00f3n (ricotta) 50 g de queso Cheddar, rallado Sal Pimienta Preparaci\u00f3n: Precalentar el horno a 220\u00b0C (horno bien caliente). Enmantecar y enharinar una tartera con el disco de masa...Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/\" \/>\n<meta property=\"og:site_name\" content=\"IreneMilito.it\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-24T16:19:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/02\/puffpastrytart2500-5a7b78fd3418c60036aa1a28.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"299\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Milito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Milito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/\",\"url\":\"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/\",\"name\":\"Pastel hojaldre liviano de zucchinis - IreneMilito.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/02\/puffpastrytart2500-5a7b78fd3418c60036aa1a28.jpg\",\"datePublished\":\"2019-02-24T16:19:58+00:00\",\"dateModified\":\"2019-02-24T16:19:58+00:00\",\"author\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/#primaryimage\",\"url\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/02\/puffpastrytart2500-5a7b78fd3418c60036aa1a28.jpg\",\"contentUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/02\/puffpastrytart2500-5a7b78fd3418c60036aa1a28.jpg\",\"width\":450,\"height\":299},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.irenemilito.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pastel hojaldre liviano de zucchinis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\",\"url\":\"https:\/\/www.irenemilito.it\/es\/\",\"name\":\"IreneMilito.it\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\",\"name\":\"Irene Milito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"caption\":\"Irene Milito\"},\"url\":\"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pastel hojaldre liviano de zucchinis - IreneMilito.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/","og_locale":"es_ES","og_type":"article","og_title":"Pastel hojaldre liviano de zucchinis","og_description":"Ingredientes: 1 disco de masa hojaldre (para tarta) 1 cucharada de mantequilla 4 zucchinis medianos, picado 3 huevos 2 cucharaditas de queso crema 4 cucharadas de reques\u00f3n (ricotta) 50 g de queso Cheddar, rallado Sal Pimienta Preparaci\u00f3n: Precalentar el horno a 220\u00b0C (horno bien caliente). Enmantecar y enharinar una tartera con el disco de masa...Read More","og_url":"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/","og_site_name":"IreneMilito.it","article_published_time":"2019-02-24T16:19:58+00:00","og_image":[{"width":450,"height":299,"url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/02\/puffpastrytart2500-5a7b78fd3418c60036aa1a28.jpg","type":"image\/jpeg"}],"author":"Irene Milito","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Irene Milito","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/","url":"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/","name":"Pastel hojaldre liviano de zucchinis - IreneMilito.it","isPartOf":{"@id":"https:\/\/www.irenemilito.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/#primaryimage"},"image":{"@id":"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/02\/puffpastrytart2500-5a7b78fd3418c60036aa1a28.jpg","datePublished":"2019-02-24T16:19:58+00:00","dateModified":"2019-02-24T16:19:58+00:00","author":{"@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43"},"breadcrumb":{"@id":"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/#primaryimage","url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/02\/puffpastrytart2500-5a7b78fd3418c60036aa1a28.jpg","contentUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/02\/puffpastrytart2500-5a7b78fd3418c60036aa1a28.jpg","width":450,"height":299},{"@type":"BreadcrumbList","@id":"https:\/\/www.irenemilito.it\/es\/pastel-hojaldre-liviano-de-zucchinis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irenemilito.it\/es\/"},{"@type":"ListItem","position":2,"name":"Pastel hojaldre liviano de zucchinis"}]},{"@type":"WebSite","@id":"https:\/\/www.irenemilito.it\/es\/#website","url":"https:\/\/www.irenemilito.it\/es\/","name":"IreneMilito.it","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43","name":"Irene Milito","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","caption":"Irene Milito"},"url":"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/19212"}],"collection":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/comments?post=19212"}],"version-history":[{"count":1,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/19212\/revisions"}],"predecessor-version":[{"id":19214,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/19212\/revisions\/19214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media\/19213"}],"wp:attachment":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media?parent=19212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/categories?post=19212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/tags?post=19212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}