{"id":18637,"date":"2019-01-27T19:39:56","date_gmt":"2019-01-27T18:39:56","guid":{"rendered":"https:\/\/www.irenemilito.it\/?p=18637"},"modified":"2019-01-27T19:39:56","modified_gmt":"2019-01-27T18:39:56","slug":"remedios-caseros-para-la-amigdalitis-o-anginas","status":"publish","type":"post","link":"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/","title":{"rendered":"Remedios caseros para la amigdalitis o anginas"},"content":{"rendered":"<p>Las amigdalitis o anginas es una inflamaci\u00f3n de las am\u00edgdalas y pueden causa irritaci\u00f3n de la boca y la garganta superior y una o ambas am\u00edgdalas. La amigdalitis tambi\u00e9n puede acompa\u00f1ar a tumores en la am\u00edgdala a causa de trauma f\u00edsico o infecci\u00f3n bacteriana que entra en la am\u00edgdala enferma. La amigdalitis no siempre se acompa\u00f1a de signos evidentes como pueden resultar en la expulsi\u00f3n de peque\u00f1as cantidades de moco, falta de apetito, apat\u00eda, salivaci\u00f3n, y dificultad para tragar que se ven en la amigdalitis severa. El agrandamiento de las am\u00edgdalas puede varias de leve a lo suficientemente grande para causar dificultad para tragar causando una respiraci\u00f3n ruidosa. La r\u00e1pida administraci\u00f3n de antibi\u00f3ticos apropiados es el tratamiento habitual para la amigdalitis bacteriana. En las personas que no responden al tratamiento inicial, las pruebas de sensibilidad farmacol\u00f3gica pueden ser necesarias para identificar el mejor curso de tratamiento.<\/p>\n<h2>Tratamiento para la amigdalitis<\/h2>\n<p>Los analg\u00e9sicos de venta libre y una dieta blanda durante unos d\u00edas son recomendables mientras duren las molestias. La mayor\u00eda de los casos de amigdalitis no requieren extirpaci\u00f3n de las am\u00edgdalas y esta \u00fanicamente se recomendar\u00e1 cuando exista un agrandamiento de las am\u00edgdalas cr\u00f3nico que interfiere con el flujo de aire.<\/p>\n<h2>La cirug\u00eda<\/h2>\n<p>La cirug\u00eda para extirpar las am\u00edgdalas se conoce como amigdalaectom\u00eda. Para los nonos con dolores de garganta leve, la espera vigilante se recomienda en lugar de una amigdalectom\u00eda. Una\u00a0amigdalectom\u00eda s\u00f3lo ser\u00e1 considerada para el dolor de garganta recurrente en ni\u00f1os y adultos, si se cumplen ciertos criterios como los que se describen a continuaci\u00f3n:<\/p>\n<ul>\n<li>Dolor de garganta causado por emigdalitis<\/li>\n<li>Episodios de dolor de garganta que son incapacitantes que impiden funcionar normalmente.<\/li>\n<li>Siete o m\u00e1s dolores de garganta cl\u00ednicamente significativos, tratados adecuadamente en el ano anterior o cinco o m\u00e1s episodios de este tipo en cada uno de los anos anteriores, o tres o m\u00e1s episodios de este tipo en cada uno de los tres anos anteriores.<\/li>\n<\/ul>\n<p>La\u00a0amigdalectom\u00eda se lleva a cabo bajo anestesia general, lo que significa que estar\u00e1 dormido durante el procedimiento. La boca se mantiene abierta para permitir al cirujano ver las am\u00edgdalas sin cicatrices de sutura. Existen varios procedimientos quir\u00fargicos que se prescribir\u00e1n en funci\u00f3n de cada caso:<\/p>\n<ul>\n<li>Cirug\u00eda de acero en fr\u00edo: Este es el m\u00e9todo m\u00e1s com\u00fan, donde se utiliza se utiliza una cuchilla quir\u00fargica para cortar las am\u00edgdalas. El sangrado se controla mediante la aplicaci\u00f3n de presi\u00f3n o los vasos sangu\u00edneos que se pueden sellar mediante calor generado por la diatermia.<\/li>\n<li>Diatermia: Que consiste en una sonda que se utiliza para destruir el tejido alrededor de las am\u00edgdalas y quitar las am\u00edgdalas, al mismo tiempo, el calor sello los vasos sangu\u00edneos para detener cualquier sangrado.<\/li>\n<li>Coblation (o ablaci\u00f3n en fr\u00edo): Este m\u00e9todo funciona de una manera similar a la diatermia, pero utiliza una temperatura inferior (60\u00b0C). es considerado menos doloroso que la diatermia.<\/li>\n<li>L\u00e1ser: Los rayos l\u00e1ser de alta frecuencia se utilizan para cortar las am\u00edgdalas y sellar los vasos sangu\u00edneos subyacentes cerrados.<\/li>\n<\/ul>\n<p>Si buscas alternativas naturales para tratar esta dolencia, te citamos algunos de los remedios caseros para las anginas m\u00e1s efectivos.<\/p>\n<ul>\n<li><b>Zumo de lim\u00f3n\u00a0y miel<\/b><\/li>\n<\/ul>\n<p>En un vaso con agua tibia, anade el zumo de un lim\u00f3n reci\u00e9n exprimido y una cucharada de miel. Haz g\u00e1rgaras con ello 3 o 4 veces al d\u00eda. Este remedio ayuda a disminuir la inflamaci\u00f3n y posibilidades de infecci\u00f3n. Despu\u00e9s de realizar las g\u00e1rgaras es bueno lavarse bien los dientes para evitar que ning\u00fan residuo pueda afectar a tus dientes y tambi\u00e9n por el efecto corrosivo que pueda tener el lim\u00f3n en las dentinas.<\/p>\n<ul>\n<li><strong>Tomillo<\/strong><\/li>\n<\/ul>\n<p>Toma un infusi\u00f3n de tomillo, el cual gracias a sus propiedades desinfectantes y antis\u00e9pticas ayudaran a tu recuperaci\u00f3n. Para prepararlo, hierve durante unos 5 minutos agua con unas cuantas hojas de tomillo. T\u00f3malo 2 o 3 veces al d\u00eda.<\/p>\n<ul>\n<li><strong>Salvia<\/strong><\/li>\n<\/ul>\n<p>Realiza un emplasto caliente con hojas de salvia. Hierve hojas de salvia, las envuelves en un pa\u00f1uelo para mantener el calor y apl\u00edcalo directamente a tu garganta. Cada vez que se enfr\u00eden sustituye las hojas por otras. Los puedes combinar tambi\u00e9n con g\u00e1rgaras de infusi\u00f3n de salvia.<\/p>\n<ul>\n<li><strong>Romero<\/strong><\/li>\n<\/ul>\n<p>Hierve en una taza vino blanco con tres cucharadas de romero. Con ello haz g\u00e1rgaras tres veces al d\u00eda.<\/p>\n<h2>Recomendaciones y consejos en el tratamiento de la amigdalitis<\/h2>\n<p>La ingesti\u00f3n probablemente ser\u00e1 dif\u00edcil despu\u00e9s de tener una amigdalectom\u00eda, sin embargo, es importante comer alimentos s\u00f3lidos, ya que ayudar\u00e1 a la garganta a sanar m\u00e1s r\u00e1pidamente. Beber mucho l\u00edquido tambi\u00e9n se recomienda en el proceso postoperatorio pero hay que evitar las bebidas \u00e1cidas como el zumo de naranja porque pueden producir molestias. Mantener una buena higiene oral, cepillarse regularmente los dientes y usar enjuague bucal puede ayudar a prevenir la infecci\u00f3n en la boca. El dolor generalmente empeora durante la primera semana despu\u00e9s de tener una amigdalectom\u00eda, pero no es una causa de preocupaci\u00f3n. No siempre es f\u00e1cil evitar el contagio de infecciones virales con los g\u00e9rmenes, sin embargo, la aplicaci\u00f3n de buenas practicas de higiene puede ayudar a prevenir la propagaci\u00f3n de infecciones.<\/p>\n<h2>Otros consejos en el tratamiento de la admigdalitis<\/h2>\n<ul>\n<li>Lavarse las manos con frecuencia<\/li>\n<li>Toser y estornudar en un pa\u00f1uelo de papel y deshacerse de ellos r\u00e1pidamente.<\/li>\n<li>Evitar compartir vasos o utensilios con personas que est\u00e1n enfermas.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las amigdalitis o anginas es una inflamaci\u00f3n de las am\u00edgdalas y pueden causa irritaci\u00f3n de la boca y la garganta superior y una o ambas am\u00edgdalas. La amigdalitis tambi\u00e9n puede acompa\u00f1ar a tumores en la am\u00edgdala a causa de trauma f\u00edsico o infecci\u00f3n bacteriana que entra en la am\u00edgdala enferma. La amigdalitis no siempre se&#8230;<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/\">Read More<\/a><\/div>\n","protected":false},"author":3,"featured_media":18638,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3999],"tags":[4104,11733],"class_list":["post-18637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dietas-y-remedios-naturales","tag-remedios-caseros","tag-remedios-caseros-para-la-amigdalitis-o-anginas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Remedios caseros para la amigdalitis o anginas - IreneMilito.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Remedios caseros para la amigdalitis o anginas\" \/>\n<meta property=\"og:description\" content=\"Las amigdalitis o anginas es una inflamaci\u00f3n de las am\u00edgdalas y pueden causa irritaci\u00f3n de la boca y la garganta superior y una o ambas am\u00edgdalas. La amigdalitis tambi\u00e9n puede acompa\u00f1ar a tumores en la am\u00edgdala a causa de trauma f\u00edsico o infecci\u00f3n bacteriana que entra en la am\u00edgdala enferma. La amigdalitis no siempre se...Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/\" \/>\n<meta property=\"og:site_name\" content=\"IreneMilito.it\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-27T18:39:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/maxresdefault.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Milito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Milito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/\",\"url\":\"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/\",\"name\":\"Remedios caseros para la amigdalitis o anginas - IreneMilito.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/maxresdefault.jpg\",\"datePublished\":\"2019-01-27T18:39:56+00:00\",\"dateModified\":\"2019-01-27T18:39:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/#primaryimage\",\"url\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/maxresdefault.jpg\",\"contentUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/maxresdefault.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.irenemilito.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Remedios caseros para la amigdalitis o anginas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\",\"url\":\"https:\/\/www.irenemilito.it\/es\/\",\"name\":\"IreneMilito.it\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\",\"name\":\"Irene Milito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"caption\":\"Irene Milito\"},\"url\":\"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Remedios caseros para la amigdalitis o anginas - IreneMilito.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/","og_locale":"es_ES","og_type":"article","og_title":"Remedios caseros para la amigdalitis o anginas","og_description":"Las amigdalitis o anginas es una inflamaci\u00f3n de las am\u00edgdalas y pueden causa irritaci\u00f3n de la boca y la garganta superior y una o ambas am\u00edgdalas. La amigdalitis tambi\u00e9n puede acompa\u00f1ar a tumores en la am\u00edgdala a causa de trauma f\u00edsico o infecci\u00f3n bacteriana que entra en la am\u00edgdala enferma. La amigdalitis no siempre se...Read More","og_url":"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/","og_site_name":"IreneMilito.it","article_published_time":"2019-01-27T18:39:56+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/maxresdefault.jpg","type":"image\/jpeg"}],"author":"Irene Milito","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Irene Milito","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/","url":"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/","name":"Remedios caseros para la amigdalitis o anginas - IreneMilito.it","isPartOf":{"@id":"https:\/\/www.irenemilito.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/#primaryimage"},"image":{"@id":"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/maxresdefault.jpg","datePublished":"2019-01-27T18:39:56+00:00","dateModified":"2019-01-27T18:39:56+00:00","author":{"@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43"},"breadcrumb":{"@id":"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/#primaryimage","url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/maxresdefault.jpg","contentUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/maxresdefault.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.irenemilito.it\/es\/remedios-caseros-para-la-amigdalitis-o-anginas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irenemilito.it\/es\/"},{"@type":"ListItem","position":2,"name":"Remedios caseros para la amigdalitis o anginas"}]},{"@type":"WebSite","@id":"https:\/\/www.irenemilito.it\/es\/#website","url":"https:\/\/www.irenemilito.it\/es\/","name":"IreneMilito.it","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43","name":"Irene Milito","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","caption":"Irene Milito"},"url":"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/18637"}],"collection":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/comments?post=18637"}],"version-history":[{"count":1,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/18637\/revisions"}],"predecessor-version":[{"id":18639,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/18637\/revisions\/18639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media\/18638"}],"wp:attachment":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media?parent=18637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/categories?post=18637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/tags?post=18637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}