{"id":18529,"date":"2019-01-23T17:06:29","date_gmt":"2019-01-23T16:06:29","guid":{"rendered":"https:\/\/www.irenemilito.it\/?p=18529"},"modified":"2019-01-23T17:06:29","modified_gmt":"2019-01-23T16:06:29","slug":"salsa-amatriciana","status":"publish","type":"post","link":"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/","title":{"rendered":"Salsa amatriciana"},"content":{"rendered":"<p><strong>Porciones:\u00a0<\/strong>2 raciones de pasta<\/p>\n<p><strong>Ingredientes:<\/strong><\/p>\n<ul>\n<li>1 cucharada de aceite de oliva<\/li>\n<li>200 gramos de tomate entero pelado en conserva<\/li>\n<li>50 gramos de bacon en tiras<\/li>\n<li>50 gramos de pecorino rallado (o en su defecto un buen queso de oveja)<\/li>\n<li>Medio vaso de vino blanco (100 mililitros)<\/li>\n<li>1 Cayena (si la quer\u00e9is picante)<\/li>\n<li>Pimienta negra molida<\/li>\n<\/ul>\n<p><b>Preparaci\u00f3n:<\/b><\/p>\n<p>Cortamos el bacon en tiras, y lo echamos en una sart\u00e9n con el aceite. Cuando empiece a tornarse transparente, a\u00f1adimos la Cayena picada. Si no quer\u00e9is picante, prescindir de la Cayena. O si la quer\u00e9is solamente con un puntito suave de picante, echarla entera, pero luego tened el cuidado de sacarla al finalizar la cocci\u00f3n de la salsa. Dejamos cocinar un par de minutos y a\u00f1adimos el vino blanco, dejando que se queme un poco el alcohol durante otro par de minutos. Quitamos el bacon de la sart\u00e9n y reservamos. En la misma sart\u00e9n, todav\u00eda con los jugos del vino, a\u00f1adimos el tomate picado y lo dejamos cocinar a fuego lento durante 15 minutos. Incorporamos el bacon que ten\u00edamos reservado y el queso rallado. Removemos todo y ya tenemos la salsa lista. Ya solo queda, como en casi todas las recetas de pasta de este tipo, echar la pasta encima de la salsa y mezclarlo bien todo. Al emplatar la pasta, echar encima un poco m\u00e1s de queso rallado al gusto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Porciones:\u00a02 raciones de pasta Ingredientes: 1 cucharada de aceite de oliva 200 gramos de tomate entero pelado en conserva 50 gramos de bacon en tiras 50 gramos de pecorino rallado (o en su defecto un buen queso de oveja) Medio vaso de vino blanco (100 mililitros) 1 Cayena (si la quer\u00e9is picante) Pimienta negra molida&#8230;<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/\">Read More<\/a><\/div>\n","protected":false},"author":3,"featured_media":18530,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3800],"tags":[11618,4117,2934,5575,3937,2982,11584,11616,11615,11617,3861],"class_list":["post-18529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas","tag-pecorino-rallado-o-en-su-defecto-un-buen-queso-de-oveja","tag-pimienta-negra-molida","tag-recetas-con-el-queso","tag-recetas-con-el-queso-italiano","tag-recetas-de-salsas","tag-recetas-de-salsas-para-pasta","tag-recetas-de-salsas-para-pastas","tag-recetas-para-amatriciana","tag-salsa-amatriciana","tag-tomate-entero-pelado-en-conserva","tag-vino-blanco"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Salsa amatriciana - IreneMilito.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salsa amatriciana\" \/>\n<meta property=\"og:description\" content=\"Porciones:\u00a02 raciones de pasta Ingredientes: 1 cucharada de aceite de oliva 200 gramos de tomate entero pelado en conserva 50 gramos de bacon en tiras 50 gramos de pecorino rallado (o en su defecto un buen queso de oveja) Medio vaso de vino blanco (100 mililitros) 1 Cayena (si la quer\u00e9is picante) Pimienta negra molida...Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/\" \/>\n<meta property=\"og:site_name\" content=\"IreneMilito.it\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-23T16:06:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/Bucatini-alla-Amatriciana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3123\" \/>\n\t<meta property=\"og:image:height\" content=\"2082\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Milito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Milito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/\",\"url\":\"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/\",\"name\":\"Salsa amatriciana - IreneMilito.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/Bucatini-alla-Amatriciana.jpg\",\"datePublished\":\"2019-01-23T16:06:29+00:00\",\"dateModified\":\"2019-01-23T16:06:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/#primaryimage\",\"url\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/Bucatini-alla-Amatriciana.jpg\",\"contentUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/Bucatini-alla-Amatriciana.jpg\",\"width\":3123,\"height\":2082},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.irenemilito.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salsa amatriciana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\",\"url\":\"https:\/\/www.irenemilito.it\/es\/\",\"name\":\"IreneMilito.it\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\",\"name\":\"Irene Milito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"caption\":\"Irene Milito\"},\"url\":\"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salsa amatriciana - IreneMilito.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/","og_locale":"es_ES","og_type":"article","og_title":"Salsa amatriciana","og_description":"Porciones:\u00a02 raciones de pasta Ingredientes: 1 cucharada de aceite de oliva 200 gramos de tomate entero pelado en conserva 50 gramos de bacon en tiras 50 gramos de pecorino rallado (o en su defecto un buen queso de oveja) Medio vaso de vino blanco (100 mililitros) 1 Cayena (si la quer\u00e9is picante) Pimienta negra molida...Read More","og_url":"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/","og_site_name":"IreneMilito.it","article_published_time":"2019-01-23T16:06:29+00:00","og_image":[{"width":3123,"height":2082,"url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/Bucatini-alla-Amatriciana.jpg","type":"image\/jpeg"}],"author":"Irene Milito","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Irene Milito","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/","url":"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/","name":"Salsa amatriciana - IreneMilito.it","isPartOf":{"@id":"https:\/\/www.irenemilito.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/#primaryimage"},"image":{"@id":"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/Bucatini-alla-Amatriciana.jpg","datePublished":"2019-01-23T16:06:29+00:00","dateModified":"2019-01-23T16:06:29+00:00","author":{"@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43"},"breadcrumb":{"@id":"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/#primaryimage","url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/Bucatini-alla-Amatriciana.jpg","contentUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2019\/01\/Bucatini-alla-Amatriciana.jpg","width":3123,"height":2082},{"@type":"BreadcrumbList","@id":"https:\/\/www.irenemilito.it\/es\/salsa-amatriciana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irenemilito.it\/es\/"},{"@type":"ListItem","position":2,"name":"Salsa amatriciana"}]},{"@type":"WebSite","@id":"https:\/\/www.irenemilito.it\/es\/#website","url":"https:\/\/www.irenemilito.it\/es\/","name":"IreneMilito.it","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43","name":"Irene Milito","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","caption":"Irene Milito"},"url":"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/18529"}],"collection":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/comments?post=18529"}],"version-history":[{"count":1,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/18529\/revisions"}],"predecessor-version":[{"id":18531,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/18529\/revisions\/18531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media\/18530"}],"wp:attachment":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media?parent=18529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/categories?post=18529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/tags?post=18529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}