{"id":17120,"date":"2018-11-20T15:55:32","date_gmt":"2018-11-20T14:55:32","guid":{"rendered":"https:\/\/www.irenemilito.it\/?p=17120"},"modified":"2018-11-20T16:37:28","modified_gmt":"2018-11-20T15:37:28","slug":"paella-mediterranea","status":"publish","type":"post","link":"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/","title":{"rendered":"Paella mediterr\u00e1nea"},"content":{"rendered":"<p><strong>Ingredientes:<\/strong><\/p>\n<ul>\n<li>900 ml de caldo de verduras o de pescado bajo en sodio, o preparado sin sal<\/li>\n<li>Una pizca grande de hebras de azafr\u00e1n<\/li>\n<li>500 g de chorizo<\/li>\n<li>400 g de filete de abadejo ahumado, sin piel<\/li>\n<li>2 cucharadas de aceite de oliva extra virgen<\/li>\n<li>1 cebolla grande, picada finamente<\/li>\n<li>2 dientes de ajo grandes, machacados<\/li>\n<li>250 g de chauchas, cortadas en trozos del tama\u00f1o de un bocado<\/li>\n<li>250 g de arroz para paella o de grano corto<\/li>\n<li>Pimienta al gusto<\/li>\n<li>150 g de arvejas congeladas<\/li>\n<li>Perejil, picado fino, para decorar<\/li>\n<\/ul>\n<p><b>Preparaci\u00f3n:<\/b><\/p>\n<p>Llevar el caldo a hervor en una olla a fuego alto. Agregar las hebras de azafr\u00e1n, bajar el fuego y dejar cocinar suavemente mientras se preparan los otros ingredientes. Retirar la piel gruesa del chorizo y rebanarlo fino. Cortar el abadejo en trozos grandes. Calentar el aceite de oliva en una paellera. Agregar el chorizo, la cebolla, el ajo y las chauchas, y fre\u00edr 2 minutos, revolviendo de vez en cuando. Agregar el arroz y revolver hasta que todos los granos est\u00e9n cubiertos de aceite. Anadir el caldo con azafr\u00e1n y revolver. Condimentar con pimienta al gusto. Llevar a hervor, bajar el fuego y cocinar 3 minutos. Incorporar poco a poco los trozos de abadejo y las arvejas. Cocinar unos 20 minutos m\u00e1s o hasta que todo el l\u00edquido se haya absorbido y el arroz est\u00e9 tierno. En la mitad del tiempo de cocci\u00f3n, revolver con cuidado para no desmenuzar demasiado el abadejo. Espolvorear con el perejil y servir de inmediato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingredientes: 900 ml de caldo de verduras o de pescado bajo en sodio, o preparado sin sal Una pizca grande de hebras de azafr\u00e1n 500 g de chorizo 400 g de filete de abadejo ahumado, sin piel 2 cucharadas de aceite de oliva extra virgen 1 cebolla grande, picada finamente 2 dientes de ajo grandes,&#8230;<\/p>\n<div class=\" [&hellip;]\"><a href=\"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/\">Read More<\/a><\/div>\n","protected":false},"author":3,"featured_media":17121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[3800],"tags":[10225,2872,5095,2873,10213,5028,2912],"class_list":["post-17120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recetas","tag-pella-mediterranea","tag-perejil","tag-recetas-con-las-especias","tag-recetas-de-carne","tag-recetas-de-cocina-espanola","tag-recetas-de-paellas","tag-recetas-espanolas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Paella mediterr\u00e1nea - IreneMilito.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pella mediterr\u00e1nea\" \/>\n<meta property=\"og:description\" content=\"Ingredientes: 900 ml de caldo de verduras o de pescado bajo en sodio, o preparado sin sal Una pizca grande de hebras de azafr\u00e1n 500 g de chorizo 400 g de filete de abadejo ahumado, sin piel 2 cucharadas de aceite de oliva extra virgen 1 cebolla grande, picada finamente 2 dientes de ajo grandes,...Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/\" \/>\n<meta property=\"og:site_name\" content=\"IreneMilito.it\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-20T14:55:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-20T15:37:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2018\/11\/2B-1000x600.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"372\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Irene Milito\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Irene Milito\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/\",\"url\":\"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/\",\"name\":\"Paella mediterr\u00e1nea - IreneMilito.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2018\/11\/2B-1000x600.jpg\",\"datePublished\":\"2018-11-20T14:55:32+00:00\",\"dateModified\":\"2018-11-20T15:37:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/#primaryimage\",\"url\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2018\/11\/2B-1000x600.jpg\",\"contentUrl\":\"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2018\/11\/2B-1000x600.jpg\",\"width\":620,\"height\":372},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.irenemilito.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paella mediterr\u00e1nea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#website\",\"url\":\"https:\/\/www.irenemilito.it\/es\/\",\"name\":\"IreneMilito.it\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43\",\"name\":\"Irene Milito\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g\",\"caption\":\"Irene Milito\"},\"url\":\"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paella mediterr\u00e1nea - IreneMilito.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/","og_locale":"es_ES","og_type":"article","og_title":"Pella mediterr\u00e1nea","og_description":"Ingredientes: 900 ml de caldo de verduras o de pescado bajo en sodio, o preparado sin sal Una pizca grande de hebras de azafr\u00e1n 500 g de chorizo 400 g de filete de abadejo ahumado, sin piel 2 cucharadas de aceite de oliva extra virgen 1 cebolla grande, picada finamente 2 dientes de ajo grandes,...Read More","og_url":"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/","og_site_name":"IreneMilito.it","article_published_time":"2018-11-20T14:55:32+00:00","article_modified_time":"2018-11-20T15:37:28+00:00","og_image":[{"width":620,"height":372,"url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2018\/11\/2B-1000x600.jpg","type":"image\/jpeg"}],"author":"Irene Milito","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Irene Milito","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/","url":"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/","name":"Paella mediterr\u00e1nea - IreneMilito.it","isPartOf":{"@id":"https:\/\/www.irenemilito.it\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/#primaryimage"},"image":{"@id":"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2018\/11\/2B-1000x600.jpg","datePublished":"2018-11-20T14:55:32+00:00","dateModified":"2018-11-20T15:37:28+00:00","author":{"@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43"},"breadcrumb":{"@id":"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/#primaryimage","url":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2018\/11\/2B-1000x600.jpg","contentUrl":"https:\/\/www.irenemilito.it\/wp-content\/uploads\/2018\/11\/2B-1000x600.jpg","width":620,"height":372},{"@type":"BreadcrumbList","@id":"https:\/\/www.irenemilito.it\/es\/paella-mediterranea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.irenemilito.it\/es\/"},{"@type":"ListItem","position":2,"name":"Paella mediterr\u00e1nea"}]},{"@type":"WebSite","@id":"https:\/\/www.irenemilito.it\/es\/#website","url":"https:\/\/www.irenemilito.it\/es\/","name":"IreneMilito.it","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irenemilito.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/6b85191f6a3b4eca504346a11bfb5a43","name":"Irene Milito","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.irenemilito.it\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5eb26e0db05f41e91aa2b9ea92d89581?s=96&d=mm&r=g","caption":"Irene Milito"},"url":"https:\/\/www.irenemilito.it\/es\/author\/irene-milito\/"}]}},"_links":{"self":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/17120"}],"collection":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/comments?post=17120"}],"version-history":[{"count":2,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/17120\/revisions"}],"predecessor-version":[{"id":17137,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/posts\/17120\/revisions\/17137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media\/17121"}],"wp:attachment":[{"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/media?parent=17120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/categories?post=17120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.irenemilito.it\/es\/wp-json\/wp\/v2\/tags?post=17120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}